{"id":2,"date":"2024-06-24T16:47:54","date_gmt":"2024-06-24T21:47:54","guid":{"rendered":"https:\/\/miplataformaeducativa.com\/es\/?page_id=2"},"modified":"2026-07-23T21:43:31","modified_gmt":"2026-07-24T02:43:31","slug":"home","status":"publish","type":"page","link":"https:\/\/miplataformaeducativa.com\/es\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"brz-root__container brz-reset-all\"><main id=\"tvbR2jtNVFMy\" class=\"brz-section brz-css-e8Aec\"><\/p>\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-rJuJy\" data-brz-custom-id=\"bEdGEWB8aZEc\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"dH2J89BoMY3f\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-wNCHt\" data-brz-custom-id=\"wshRq7giRebI\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-css-ktMg5 brz-wrapper\">\n<div class=\"brz-image brz-css-ag_La\" data-brz-custom-id=\"bHYWymfJbKdP\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-kLU0k\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/logo-mpe-actual-285x63x0x0x285x63x1719330466.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/logo-mpe-actual-570x126x0x0x570x126x1719330466.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/logo-mpe-actual-179x40x0x0x179x40x1719330466.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/logo-mpe-actual-358x80x0x0x358x80x1719330466.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/logo-mpe-actual-301x67x0x0x301x67x1719330466.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/logo-mpe-actual-602x134x0x0x602x134x1719330466.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/logo-mpe-actual-285x63x0x0x285x63x1719330466.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-vfYS5\" data-brz-custom-id=\"qn65oNuJltlA\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-wv3ca\">\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-wrapper brz-animated brz-css-tdJwy brz-css-zb06k\" data-animationid=\"gjVD7WU8myOt\">\n<div class=\"brz-menu-simple brz-css-wbADt brz-css-wNeDr\">\n<div style=\"min-height:20px\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><a class=\"brz-a brz-anchor brz-container-link\" href=\"#inicio\" target=\"_self\" rel=\"noopener\" data-brz-link-type=\"anchor\"><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/main><\/p>\n<section id=\"inicio\" data-brz-iteration-count=\"1\" class=\"brz-section brz-css-e8Aec brz-animated brz-css-nI37P brz-css-zjSZz\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-g_nvx\" data-brz-custom-id=\"mcEZIWwFgJcf\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-image\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"bY8bo7o8gQCM\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-hpS7A\" data-brz-custom-id=\"mgpIsWodGxt0\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"gjxDnYM0DuRY\">\n<div data-brz-translate-text=\"1\">\n<h1 class=\"brz-tp-lg-heading1 brz-ls-xs-m_1 brz-lh-xs-1_3 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-overpass brz-ft-google brz-tp-xs-empty brz-fs-xs-30 brz-fss-xs-px brz-fw-xs-600 brz-css-z9epb\" data-uniq-id=\"hEEHB\" data-generated-css=\"brz-css-cEYHD\"><span class=\"brz-cp-color8\" style=\"color: rgba(var(--brz-global-color8),1);\">Agentes Capacitadores Externos<\/span><\/h1>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-tCqkR brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"uJDrGNB1xvvt\">\n<div data-brz-translate-text=\"1\">\n<h3 class=\"brz-tp-lg-heading3 brz-fss-xs-px brz-fw-xs-700 brz-ls-xs-m_0_5 brz-lh-xs-1_3 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-overpass brz-ft-google brz-tp-xs-empty brz-fs-xs-16 brz-css-yO0lk\" data-uniq-id=\"gpkLF\" data-generated-css=\"brz-css-p63P4\"><span class=\"brz-cp-color7\" style=\"color: white;\">Secretar\u00eda de Trabajo y Previsi\u00f3n social<\/span><\/h3>\n<h3 class=\"brz-tp-lg-heading3 brz-fss-xs-px brz-fw-xs-700 brz-ls-xs-m_0_5 brz-lh-xs-1_3 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-overpass brz-ft-google brz-tp-xs-empty brz-fs-xs-16 brz-css-pTNJ4\" data-uniq-id=\"xXMYh\" data-generated-css=\"brz-css-un7pz\"><span class=\"brz-cp-color7\" style=\"color: white;\">Registro: FTS171122-K12-0013<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-kPiSF brz-wrapper\">\n<div class=\"brz-image brz-css-wBjMo\" data-brz-custom-id=\"cIxgGFHerTRO\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-wCexs\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-225x62x0x0x225x62x1719314715.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-450x124x0x0x450x124x1719314715.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-144x40x0x0x144x40x1719314715.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-288x80x0x0x288x80x1719314715.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-129x36x0x0x129x36x1719314715.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-258x72x0x0x258x72x1719314715.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-225x62x0x0x225x62x1719314715.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-q9170\" data-brz-custom-id=\"k149gh_p9Bs3\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-v7RqJ\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"qgMFayPoXDk9\">\n<div data-brz-translate-text=\"1\">\n<h3 class=\"brz-fs-xs-31 brz-tp-xs-empty brz-ft-google brz-ff-overpass brz-fsft-xs-0 brz-fwdth-xs-100 brz-vfw-xs-400 brz-lh-xs-1_4 brz-ls-xs-m_1_5 brz-fw-xs-700 brz-fss-xs-px brz-text-lg-center brz-tp-lg-empty brz-fs-lg-35 brz-fss-lg-px brz-fw-lg-700 brz-ls-lg-m_1_5 brz-lh-lg-1_4 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-rf0qX\" data-uniq-id=\"t6yau\" data-generated-css=\"brz-css-e6Wq1\"><span style=\"color: rgb(37, 116, 68);\">Ingresa a tu curso<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-mIqnW brz-wrapper\">\n<div class=\"brz-wp-shortcode brz-css-kqska\" data-brz-custom-id=\"ozK61yRkOKbt\">\n<div><form id=\"loginForm\" method=\"POST\" action=\"https:\/\/hoymecapacito.com\/acciones\/login.php\">\n<div class=\"uk-width-1-1 uk-margin\">\n\t\t<label class=\"uk-form-label\" for=\"email\"  style=\"color:#247444;    font-weight: bold;    margin: 0;\">Correo Electr\u00f3nico<\/label><br \/>\n\t\t<input id=\"email\" class=\"uk-input uk-form-large\" style=\"font-size: 1rem;\" name=\"username\" type=\"email\" placeholder=\"Digita tu Correo Electr\u00f3nico\">\n\t<\/div>\n<div class=\"uk-width-1-1 uk-margin\">\n\t\t<label class=\"uk-form-label\" for=\"password\"  style=\"color:#247444;    font-weight: bold;    margin: 0;\">Contrase\u00f1a<\/label><br \/>\n\t\t<input id=\"password\" class=\"uk-input uk-form-large\" style=\"font-size: 1rem;\" type=\"password\" name=\"password\" placeholder=\"Digita tu Contrase\u00f1a\" >\n\t<\/div>\n<div class=\"uk-width-1-1 uk-margin uk-text-center\"  style=\"color:#247444\">\n\t\t<a class=\"uk-text-small uk-link-muted\" href=\"#modalpass\" uk-toggle><strong style=\"color:#247444\">\u00bfOlvidaste tu contrase\u00f1a?<\/strong><\/a>\n\t<\/div>\n<div class=\"uk-width-1-1 uk-text-center\">\n\t\t<input type=\"submit\" name=\"entrar\"  class=\"uk-button uk-button-large uk-text-muted\" style=\" color: #fff!important;background-color: #247444;    padding: 15px 20px;    border-radius: 20px;\" value=\"INICIAR\"\/>\n\t<\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"nosotros-2\" data-brz-iteration-count=\"1\" class=\"brz-section brz-css-e8Aec brz-animated brz-css-abRrb brz-css-gok1I\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-q_yFv\" data-brz-custom-id=\"idNSwjYim5Eb\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"by1q3TCzw63X\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-iNdFK\" data-brz-custom-id=\"sHqECD0TPT6R\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"sOLDsluE8GsJ\">\n<div data-brz-translate-text=\"1\">\n<h2 data-generated-css=\"brz-css-fgI4U\" data-uniq-id=\"jkdXY\" class=\"brz-tp-lg-heading2 brz-css-nbKco\"><strong style=\"color: rgb(0, 0, 0);\">Selecci\u00f3n de Cursos<\/strong><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"yU_tztx1IYXX\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-c6zDf\" data-brz-custom-id=\"chdnpnmwhQQS\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-e61Th\">\n<div id class=\"brz-css-zwtwv brz-css-bZk8Z brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"vbKwVrDaTLXd\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-mt-lg-0 brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-lh-lg-1_9 brz-ls-lg-0 brz-fw-lg-400 brz-fss-lg-px brz-fs-lg-16 brz-tp-lg-empty brz-text-lg-center brz-fss-xs-px brz-fw-xs-400 brz-ls-xs-0 brz-lh-xs-1_9 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-roboto brz-ft-google brz-tp-xs-empty brz-fs-xs-14 brz-css-qrfp6\" data-uniq-id=\"j66KK\" data-generated-css=\"brz-css-arGhH\"><strong style=\"background-color: rgb(255, 255, 255); color: rgb(30, 114, 108);\"> Excel B\u00e1sico <\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"kv77Ted4OApH\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-e8d1s\" data-brz-custom-id=\"pdHWOqUmiNi1\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-css-jDwaP brz-wrapper\">\n<div class=\"brz-image brz-css-ya9H5\" data-brz-custom-id=\"rWvnN3spr_R9\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-lHbMz brz-css-vMePl\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-wxTnw\" data-brz-custom-id=\"mmvdmhpXEZoA\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-ere6x\">\n<div id class=\"brz-css-zwtwv brz-css-nWyae brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"p0sAsO4FmRRK\">\n<div data-brz-translate-text=\"1\">\n<h4 class=\"brz-text-lg-center brz-tp-lg-heading4 brz-tp-xs-empty brz-fs-xs-25 brz-fss-xs-px brz-fw-xs-700 brz-ls-xs-0 brz-lh-xs-1_4 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-overpass brz-ft-google brz-css-oul50\" data-generated-css=\"brz-css-xbX65\" data-uniq-id=\"aAciX\"><strong class=\"brz-cp-color7\" style=\"color: white;\">$199 <\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-xXRrG\" data-brz-custom-id=\"au41dhStevOF\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-zyGSa\">\n<div id class=\"brz-css-zwtwv brz-css-jUfyl brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"pnf3ft6WSsdn\">\n<div data-brz-translate-text=\"1\">\n<h4 class=\"brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-lh-lg-1_5 brz-ls-lg-m_0_5 brz-fw-lg-700 brz-fss-lg-px brz-fs-lg-10 brz-ft-google brz-ff-overpass brz-tp-lg-empty brz-text-lg-center brz-css-novaK\" data-generated-css=\"brz-css-opMWY\" data-uniq-id=\"ghE8e\"><strong class=\"brz-cp-color7\" style=\"color: white;\">D\u00f3lares Americanos<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-x7bTU\" data-brz-custom-id=\"nE8utslKJmcE\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-qHDPH\">\n<div id class=\"brz-css-zwtwv brz-css-hdOh4 brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"ufqTkkCDdxu0\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-text-lg-center brz-tp-lg-empty brz-fs-lg-16 brz-fss-lg-px brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1_9 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-mt-lg-0 brz-fss-xs-px brz-fw-xs-400 brz-ls-xs-0 brz-lh-xs-1_9 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-roboto brz-ft-google brz-tp-xs-empty brz-fs-xs-14 brz-css-wganI\" data-generated-css=\"brz-css-nLhsA\" data-uniq-id=\"bQND4\"><strong style=\"color: rgb(30, 114, 108); background-color: rgb(255, 255, 255);\"> <\/strong><strong style=\"color: rgb(14, 113, 57); background-color: rgb(255, 255, 255);\">Excel Avanzado<\/strong><strong style=\"color: rgb(30, 114, 108); background-color: rgb(255, 255, 255);\"> <\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"w7UEF1IrDfdn\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-b7npI\" data-brz-custom-id=\"au5SGnzcal5_\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-bdaHg\">\n<div id class=\"brz-css-zwtwv brz-css-lUwBG brz-wrapper\">\n<div class=\"brz-image brz-css-juv3D\" data-brz-custom-id=\"r02Y7gerkAPE\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-dkJRZ brz-css-hyqt7\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-xDb2H\" data-brz-custom-id=\"wkTMaIfjzC6E\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-nmwHG\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"zG6gvchoFNaS\">\n<div data-brz-translate-text=\"1\">\n<h4 class=\"brz-text-lg-center brz-tp-lg-heading4 brz-tp-xs-empty brz-fs-xs-25 brz-fss-xs-px brz-fw-xs-700 brz-ls-xs-0 brz-lh-xs-1_4 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-overpass brz-ft-google brz-css-aIlg8\" data-uniq-id=\"mCiUi\" data-generated-css=\"brz-css-elwbH\"><strong class=\"brz-cp-color7\" style=\"color: white;\">$399 <\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-vg5x7\" data-brz-custom-id=\"loGNLS6bQolu\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-naOYo\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"rX9_2XfIoZTn\">\n<div data-brz-translate-text=\"1\">\n<h4 class=\"brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-lh-lg-1_5 brz-ls-lg-m_0_5 brz-fw-lg-700 brz-fss-lg-px brz-fs-lg-10 brz-ft-google brz-ff-overpass brz-tp-lg-empty brz-text-lg-center brz-css-x81aF\" data-generated-css=\"brz-css-l2mlc\" data-uniq-id=\"xwTSv\"><strong class=\"brz-cp-color7\" style=\"color: white;\">D\u00f3lares  Americanos<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-gaR_L\" data-brz-custom-id=\"o71t7bqpZxfh\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-iiLdb\">\n<div id class=\"brz-css-zwtwv brz-css-k7FNN brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"ghIvS1FbJavO\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-text-lg-center brz-tp-lg-empty brz-fs-lg-16 brz-fss-lg-px brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1_9 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-mt-lg-0 brz-fss-xs-px brz-fw-xs-400 brz-ls-xs-0 brz-lh-xs-1_9 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-roboto brz-ft-google brz-tp-xs-empty brz-fs-xs-14 brz-css-jpaKX\" data-generated-css=\"brz-css-ydeSr\" data-uniq-id=\"nn8Mw\"><strong style=\"color: rgb(30, 114, 108); background-color: rgb(255, 255, 255);\"> <\/strong><strong style=\"color: rgb(14, 113, 57); background-color: rgb(255, 255, 255);\">VBA Excel<\/strong><strong style=\"color: rgb(30, 114, 108); background-color: rgb(255, 255, 255);\"> <\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"bj6WFCsvkwzD\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-mswJJ\" data-brz-custom-id=\"mCYuRpbq2RxJ\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-xlVTw\">\n<div id class=\"brz-css-zwtwv brz-css-cj8iq brz-wrapper\">\n<div class=\"brz-image brz-css-gqv3u\" data-brz-custom-id=\"uK6TC8tAfkvC\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-j7bfl brz-css-uQbGp\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/08\/excel.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-flbBc\" data-brz-custom-id=\"yseBJEBipWpw\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-z6uJm\">\n<div id class=\"brz-css-zwtwv brz-css-xsEm3 brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"lY_IdDEsLk0t\">\n<div data-brz-translate-text=\"1\">\n<h4 class=\"brz-tp-lg-heading4 brz-text-lg-center brz-tp-xs-empty brz-fs-xs-25 brz-fss-xs-px brz-fw-xs-700 brz-ls-xs-0 brz-lh-xs-1_4 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-overpass brz-ft-google brz-css-f5BAb\" data-generated-css=\"brz-css-mDZ2p\" data-uniq-id=\"cqlat\"><strong class=\"brz-cp-color7\" style=\"color: white;\">$499 <\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-aOEYH\" data-brz-custom-id=\"cYI1Z_CZc3_y\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-mIlgR\">\n<div id class=\"brz-css-zwtwv brz-css-iDq0H brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"kgw7myla5dqv\">\n<div data-brz-translate-text=\"1\">\n<h4 class=\"brz-text-lg-center brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-10 brz-fss-lg-px brz-fw-lg-700 brz-ls-lg-m_0_5 brz-lh-lg-1_5 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-i6pFs\" data-uniq-id=\"nQQRH\" data-generated-css=\"brz-css-uFAA_\"><strong class=\"brz-cp-color7\" style=\"color: white;\">D\u00f3lares Americanos<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"impacto\" data-brz-iteration-count=\"1\" class=\"brz-section brz-css-e8Aec brz-animated brz-css-vJLbH brz-css-vg9rs\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-gxtCi\" data-brz-custom-id=\"iWO_dWTUQj5n\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"syJ0c1IKRNGp\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-lh-xs-1_1 brz-ls-xs-0 brz-fw-xs-400 brz-fss-xs-em brz-ft-google brz-ff-overpass brz-fsft-xs-0 brz-fwdth-xs-100 brz-vfw-xs-400 brz-text-lg-center brz-fss-lg-em brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1_9 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-lg-empty brz-fs-lg-3 brz-tp-xs-empty brz-fs-xs-2 brz-css-g0aLN\" data-generated-css=\"brz-css-h4HqB\" data-uniq-id=\"m4J2z\"><span class=\"brz-cp-color7\" style=\"color: lime;\">Beneficiados con nuestra capacitaci\u00f3n innovadora<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"dD6Z45bEbiNf\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-lcP2n\" data-brz-custom-id=\"b2z1bn_PY_lb\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-aBhaG\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"tzCW3KCbJhNV\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-bA4rk\" data-brz-custom-id=\"gXMHzlIAFUV9\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-gapYa\">\n<div id class=\"brz-css-zwtwv brz-css-z6Kkc brz-wrapper\">\n<div class=\"brz-image brz-css-pgj78\" data-brz-custom-id=\"hearo3BDQ9jq\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-cE1Yn\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen4-83x83x0x0x83x83x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen4-166x166x0x0x166x166x1719314418.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen4-45x45x0x0x45x45x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen4-90x90x0x0x90x90x1719314418.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen4-124x124x0x0x124x124x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen4-248x248x0x0x248x248x1719314418.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen4-83x83x0x0x83x83x1719314418.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-t73xr\" data-brz-custom-id=\"nJq7T6hmlhWD\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-qYuAT\">\n<div id class=\"brz-css-zwtwv brz-css-iV9UM brz-wrapper\">\n<div class=\"brz-image brz-css-mandc\" data-brz-custom-id=\"hDbmrP5ZSIxM\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-rzWa2\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen3-83x83x0x0x83x83x1719314419.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen3-166x166x0x0x166x166x1719314419.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen3-45x45x0x0x45x45x1719314419.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen3-90x90x0x0x90x90x1719314419.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen3-124x124x0x0x124x124x1719314419.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen3-248x248x0x0x248x248x1719314419.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen3-83x83x0x0x83x83x1719314419.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-h0eGB\" data-brz-custom-id=\"aWc8997WmpwP\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-yw_p8\">\n<div id class=\"brz-css-zwtwv brz-css-dzEbu brz-wrapper\">\n<div class=\"brz-image brz-css-u2Pfh\" data-brz-custom-id=\"haaiY8Phmdl3\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-mijp6\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen2-83x83x0x0x83x83x1719314419.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen2-166x166x0x0x166x166x1719314419.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen2-45x45x0x0x45x45x1719314419.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen2-90x90x0x0x90x90x1719314419.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen2-124x124x0x0x124x124x1719314419.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen2-248x248x0x0x248x248x1719314419.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen2-83x83x0x0x83x83x1719314419.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63 brz-css-qjpTB\" data-brz-custom-id=\"jV97G6lojZ8Q\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-cEWhD\" data-brz-custom-id=\"vU9dmThqACPC\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-jtBoX\">\n<div id class=\"brz-css-zwtwv brz-css-k2zMD brz-wrapper\">\n<div class=\"brz-image brz-css-uYYPJ\" data-brz-custom-id=\"bRWFXMAJ6mMn\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-xbp1B\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen7-83x83x0x0x83x83x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen7-166x166x0x0x166x166x1719314418.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen7-45x45x0x0x45x45x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen7-90x90x0x0x90x90x1719314418.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen7-119x119x0x0x119x119x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen7-238x238x0x0x238x238x1719314418.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen7-83x83x0x0x83x83x1719314418.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-i9LUL\" data-brz-custom-id=\"ztkLYbY7mrpU\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-eEX2n\">\n<div id class=\"brz-css-zwtwv brz-css-fOXF9 brz-wrapper\">\n<div class=\"brz-image brz-css-x7F7I\" data-brz-custom-id=\"qIXT3_navKSn\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-ykBpF\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen6-83x83x0x0x83x83x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen6-166x166x0x0x166x166x1719314418.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen6-45x45x0x0x45x45x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen6-90x90x0x0x90x90x1719314418.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen6-123x123x0x0x123x123x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen6-246x246x0x0x246x246x1719314418.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen6-83x83x0x0x83x83x1719314418.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-ljNiN\" data-brz-custom-id=\"xZnhWk5gfmI1\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-apJO9\">\n<div id class=\"brz-css-zwtwv brz-css-coqUL brz-wrapper\">\n<div class=\"brz-image brz-css-x07D2\" data-brz-custom-id=\"tqF_X4dX7bN3\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-rDn4X\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen5-83x83x0x0x83x83x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen5-166x166x0x0x166x166x1719314418.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen5-45x45x0x0x45x45x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen5-90x90x0x0x90x90x1719314418.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen5-127x127x0x0x127x127x1719314418.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen5-254x254x0x0x254x254x1719314418.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen5-83x83x0x0x83x83x1719314418.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"nZUVe8vZjemy\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-uFhA4\" data-brz-custom-id=\"fvP7gNGK4zUZ\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-pnF5I\">\n<div id class=\"brz-css-zwtwv brz-css-tbJxT brz-wrapper\">\n<div data-brz-start=\"0\" data-brz-end=\"12000\" data-brz-duration=\"2\" data-brz-separator=\",\" data-brz-type=\"simple\" class=\"brz-counter brz-counter-simple brz-css-sk61e brz-css-tPh87\" data-brz-custom-id=\"ysIg0VeR1_mA\">\n<div class=\"brz-counter-figures brz-css-m0XHC brz-css-z5f8u\"><span>+ <\/span><span class=\"brz-counter-numbers\">0<\/span><\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"yyRV4OCLZeum\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-lh-lg-1_1 brz-ls-lg-0 brz-fw-lg-400 brz-fss-lg-px brz-fs-lg-22 brz-tp-lg-empty brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-fss-sm-px brz-fw-sm-400 brz-ls-sm-0 brz-lh-sm-1_1 brz-vfw-sm-400 brz-fwdth-sm-100 brz-fsft-sm-0 brz-ff-overpass brz-ft-google brz-tp-sm-empty brz-fs-sm-19 brz-css-ssV1_\" data-generated-css=\"brz-css-xZequ\" data-uniq-id=\"nHR8Q\"><span class=\"brz-cp-color8\" style=\"color: rgba(var(--brz-global-color8),1);\">Personas en proceso de formaci\u00f3n<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-wp8gR\" data-brz-custom-id=\"giA6gp_gkrhl\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-xsMvl\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"pZza4qJxupZA\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-jACun\" data-brz-custom-id=\"juBeXMaVHi7y\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-zGcRL\">\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-css-mzqnU brz-wrapper brz-animated brz-css-juFNs brz-css-wKzxN\" data-animationid=\"r63gL_VYyxgC\">\n<div data-brz-start=\"0\" data-brz-end=\"9000\" data-brz-duration=\"2\" data-brz-separator=\",\" data-brz-type=\"simple\" class=\"brz-counter brz-counter-simple brz-css-sk61e brz-css-iIPlL\" data-brz-custom-id=\"k4SH0Of8qRem\">\n<div class=\"brz-counter-figures brz-css-m0XHC brz-css-cDDHk\"><span>+ <\/span><span class=\"brz-counter-numbers\">0<\/span><\/div>\n<\/div>\n<\/div>\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-css-nVeed brz-wrapper brz-animated brz-css-juFNs brz-css-wT7dp\" data-animationid=\"fAAGwbs3qTVo\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"x0iUXxowTbCA\">\n<div data-brz-translate-text=\"1\">\n<p data-uniq-id=\"dqQTd\" data-generated-css=\"brz-css-fMBt7\" class=\"brz-fss-lg-em brz-fw-lg-700 brz-ls-lg-0 brz-lh-lg-1 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-1 brz-css-odjIQ\"><span style=\"color: rgb(37, 82, 21);\">Empresas capacitadas<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-zPzdz brz-wrapper\">\n<div class=\"brz-image brz-css-oTQZQ\" data-brz-custom-id=\"fIeQZhvRxa8m\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-j_EIE\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen8-77x77x0x0x77x77x1719314718.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen8-154x154x0x0x154x154x1719314718.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen8-49x49x0x0x49x49x1719314718.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen8-98x98x0x0x98x98x1719314718.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen8-98x98x0x0x98x98x1719314718.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen8-196x196x0x0x196x196x1719314718.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen8-77x77x0x0x77x77x1719314718.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"le4YACtIlLKo\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-smoNn\" data-brz-custom-id=\"xZG15eAYgRgJ\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-khD_q\">\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-css-lQ6n7 brz-wrapper brz-animated brz-css-juFNs brz-css-mR9sX\" data-animationid=\"epPRq7FtM1TA\">\n<div data-brz-start=\"0\" data-brz-end=\"100000\" data-brz-duration=\"2\" data-brz-separator=\",\" data-brz-type=\"simple\" class=\"brz-counter brz-counter-simple brz-css-sk61e brz-css-pUM1_\" data-brz-custom-id=\"bSN7FUck0Kx3\">\n<div class=\"brz-counter-figures brz-css-m0XHC brz-css-eHCuJ\"><span>+ <\/span><span class=\"brz-counter-numbers\">0<\/span><\/div>\n<\/div>\n<\/div>\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-css-xeKvn brz-wrapper brz-animated brz-css-juFNs brz-css-gIDN_\" data-animationid=\"mcKADwRCwmRe\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"po2B5mz_pFFM\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-tp-lg-empty brz-fs-lg-1 brz-fss-lg-em brz-fw-lg-700 brz-ls-lg-0 brz-lh-lg-1_9 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-fss-sm-px brz-fw-sm-700 brz-ls-sm-0 brz-lh-sm-1_2 brz-vfw-sm-400 brz-fwdth-sm-100 brz-fsft-sm-0 brz-ff-overpass brz-ft-google brz-tp-sm-empty brz-fs-sm-14 brz-css-aZgNT\" data-generated-css=\"brz-css-nLfYs\" data-uniq-id=\"nPF5_\"><span style=\"color: rgb(37, 82, 21);\">Trabajadores beneficiados<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-okNzP brz-wrapper\">\n<div class=\"brz-image brz-css-tdtF1\" data-brz-custom-id=\"qLOPxJhB15Jo\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-tryor\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen9-77x77x0x0x77x77x1719314717.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen9-154x154x0x0x154x154x1719314717.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen9-49x49x0x0x49x49x1719314717.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen9-98x98x0x0x98x98x1719314717.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen9-98x98x0x0x98x98x1719314717.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen9-196x196x0x0x196x196x1719314717.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/Imagen9-77x77x0x0x77x77x1719314717.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-xs0T1\" data-brz-custom-id=\"cVXqUmUkdB0F\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-wrapper brz-animated brz-css-uL6Lx brz-css-pkc4a\" data-animationid=\"fw9ImjgzYkUU\">\n<div data-brz-start=\"0\" data-brz-end=\"86\" data-brz-duration=\"4\" data-brz-separator=\",\" data-brz-type=\"radial\" class=\"brz-counter brz-counter-radial brz-css-sk61e brz-css-czWPU\" data-brz-custom-id=\"lwhwVS3PXC3p\">\n<div class=\"brz-counter-chart brz-counter-chart-radial\"><svg class=\"\" viewbox=\"0 0 32 32\"><circle class=\"brz-counter-radial-chart\" r=\"14.75\" cx=\"16\" cy=\"16\"\/><circle class=\"brz-counter-pie-chart brz-counter-chart-radial brz-css-koUaI brz-css-kXPvW\" r=\"16\" cx=\"16\" cy=\"16\"\/><\/svg><\/div>\n<div class=\"brz-counter-figures brz-css-m0XHC brz-css-hjTMr\"><span class=\"brz-counter-numbers\">0<\/span><span> %<\/span><\/div>\n<\/div>\n<\/div>\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-wrapper brz-animated brz-css-uL6Lx brz-css-bP7Sq\" data-animationid=\"s74MR9DXSQxK\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"dgAkVK9csQcm\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-fs-xs-2 brz-tp-xs-empty brz-ft-google brz-ff-overpass brz-fsft-xs-0 brz-fwdth-xs-100 brz-vfw-xs-400 brz-lh-xs-1 brz-ls-xs-0 brz-fw-xs-400 brz-fss-xs-em brz-text-lg-center brz-tp-lg-empty brz-fs-lg-2 brz-fss-lg-em brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-nK5Eb\" data-uniq-id=\"n4rMt\" data-generated-css=\"brz-css-oPs5C\"><span style=\"color: rgb(0, 243, 1);\">De los estudiantes<\/span><\/p>\n<p class=\"brz-fs-xs-2 brz-tp-xs-empty brz-ft-google brz-ff-overpass brz-fsft-xs-0 brz-fwdth-xs-100 brz-vfw-xs-400 brz-lh-xs-1 brz-ls-xs-0 brz-fw-xs-400 brz-fss-xs-em brz-text-lg-center brz-tp-lg-empty brz-fs-lg-2 brz-fss-lg-em brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-sm-empty brz-fs-sm-1 brz-fss-sm-em brz-fw-sm-400 brz-ls-sm-0 brz-lh-sm-1 brz-vfw-sm-400 brz-fwdth-sm-100 brz-fsft-sm-0 brz-css-wJRpF\" data-uniq-id=\"gqs5l\" data-generated-css=\"brz-css-wSdAW\"><span style=\"color: rgb(0, 243, 1);\">inscritos se certificaron<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-image brz-css-wr23l\" data-brz-custom-id=\"iKAMf42vq2vb\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-v9QSp\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-180x50x0x0x180x50x1719314715.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-360x100x0x0x360x100x1719314715.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-113x31x0x0x113x31x1719314715.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-226x62x0x0x226x62x1719314715.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-215x59x0x0x215x59x1719314715.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-430x118x0x0x430x118x1719314715.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/stp-balnco-180x50x0x0x180x50x1719314715.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"proposito\" data-brz-iteration-count=\"1\" class=\"brz-section brz-css-e8Aec brz-animated brz-css-abRrb brz-css-ko9OM\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-rfmR2\" data-brz-custom-id=\"w3pHkR7RIDY9\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"ciORbWk8IQYl\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-neasu\" data-brz-custom-id=\"qkhCgV3W3p_x\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"kaBVDH2DJOii\">\n<div data-brz-translate-text=\"1\">\n<h1 class=\"brz-text-lg-center brz-tp-lg-heading1 brz-css-hKA1Q\" data-uniq-id=\"sS6KJ\" data-generated-css=\"brz-css-ppd1V\"><span style=\"color: rgb(0, 0, 0);\">Prop\u00f3sito<\/span><\/h1>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-vh1Wu brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"mwWmSoHFOcQp\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-fs-xs-2 brz-tp-xs-empty brz-ft-google brz-ff-overpass brz-fsft-xs-0 brz-fwdth-xs-100 brz-vfw-xs-400 brz-lh-xs-1_1 brz-ls-xs-0_7 brz-fw-xs-400 brz-fss-xs-em brz-text-xs-justify brz-text-lg-justify brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-lh-lg-1_1 brz-ls-lg-0_7 brz-fw-lg-400 brz-fss-lg-em brz-fs-lg-2 brz-tp-lg-empty ql-align-justify brz-lh-sm-1_1 brz-vfw-sm-400 brz-fwdth-sm-100 brz-fsft-sm-0 brz-tp-sm-empty brz-fs-sm-2 brz-fss-sm-em brz-fw-sm-400 brz-ls-sm-0 brz-css-kgLE3\" data-uniq-id=\"u3Fj2\" data-generated-css=\"brz-css-eGlAx\"><span style=\"color: rgb(0, 0, 0);\">Nuestro objetivo es empoderar personas con el conocimiento y aprovechamiento de las nuevas tecnolog\u00edas, para un mercado laboral en constante evoluci\u00f3n.<\/span><\/p>\n<p class=\"brz-tp-lg-paragraph brz-css-pM_p6\" data-uniq-id=\"zPKhl\" data-generated-css=\"brz-css-cXGgT\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-hQ0XS\" data-brz-custom-id=\"zAQry9IqhPg6\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-css-y01Vf brz-wrapper\">\n<div class=\"brz-image brz-css-hSrj6\" data-brz-custom-id=\"umnfWsMaAc5w\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-cBmaA\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section4-359x242x0x0x359x242x1719269108.jpg 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section4-718x484x0x0x718x484x1719269108.jpg 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section4-227x153x0x0x227x153x1719269108.jpg 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section4-454x306x0x0x454x306x1719269108.jpg 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section4-430x290x0x0x430x290x1719269108.jpg 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section4-860x580x0x0x860x580x1719269108.jpg 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section4-359x242x0x0x359x242x1719269108.jpg\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"nosotros\" data-brz-iteration-count=\"1\" class=\"brz-section brz-css-e8Aec brz-animated brz-css-abRrb brz-css-pmZjX\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-maDcF\" data-brz-custom-id=\"h_MzPyPmjmS2\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"aFNKNfUNvO_w\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-mfz3T\" data-brz-custom-id=\"uB7JPKtc0GUY\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-css-rC7Hy brz-wrapper brz-animated brz-css-juFNs brz-css-kStpt\" data-animationid=\"e7fQ58QhLkjh\">\n<div class=\"brz-image brz-css-zvm8b\" data-brz-custom-id=\"dubCnLtsrCoP\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-ghb8r\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section2-477x269x59x0x358x269x1719266787.jpg 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section2-954x538x118x0x716x538x1719266787.jpg 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section2-300x169x37x0x225x169x1719266787.jpg 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section2-600x338x74x0x450x338x1719266787.jpg 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section2-573x323x71x0x430x323x1719266787.jpg 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section2-1146x646x142x0x860x646x1719266787.jpg 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/brizy\/imgs\/section2-477x269x59x0x358x269x1719266787.jpg\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-s8zSO\" data-brz-custom-id=\"zojkobMJwv2E\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-wrapper brz-animated brz-css-qiTeq brz-css-h6H0P\" data-animationid=\"sE7gLO34llj9\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"vnlPSGx2MfxV\">\n<div data-brz-translate-text=\"1\">\n<h1 class=\"brz-lh-lg-1_1 brz-ls-lg-m_1 brz-fw-lg-700 brz-fss-lg-em brz-fs-lg-4 brz-tp-lg-empty brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-text-lg-center brz-fss-xs-em brz-fw-xs-700 brz-ls-xs-m_1 brz-lh-xs-1_1 brz-vfw-xs-400 brz-fwdth-xs-100 brz-fsft-xs-0 brz-ff-overpass brz-ft-google brz-tp-xs-empty brz-fs-xs-3 brz-css-dEBBg\" data-uniq-id=\"tZViX\" data-generated-css=\"brz-css-rXcoU\">Nosotros<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<div id data-brz-iteration-count=\"1\" class=\"brz-css-zwtwv brz-wrapper brz-animated brz-css-qiTeq brz-css-fm3MN\" data-animationid=\"qQTqMBX2tT3K\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"ot1dZDW50aE0\">\n<div data-brz-translate-text=\"1\">\n<p data-uniq-id=\"bBtQ2\" data-generated-css=\"brz-css-y1z_R\" class=\"brz-text-lg-center brz-fss-lg-em brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1_1 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-2 brz-css-uFgBK\"><span style=\"color: rgb(37, 82, 21);\">Nuestra misi\u00f3n es capacitar a personas de todas las edades y perfiles de habla hispana, proporcionando formaci\u00f3n de alta calidad y accesible.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"producto\" class=\"brz-section brz-css-e8Aec\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-o0mv8\" data-brz-custom-id=\"lPh5VgpPBYd5\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"j25goqltT3mi\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-a1MLA\" data-brz-custom-id=\"m6rpyF4yhRHv\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"yhp28Smm0dOH\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-sJ9YR\" data-brz-custom-id=\"nX0cW6Lw35Fm\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-image brz-css-z988o\" data-brz-custom-id=\"eLJux2qAR8Da\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-nA9t3 brz-css-vxAhz\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/basico.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/basico.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/basico.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/basico.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/basico.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/basico.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/basico.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-yL67F\" data-brz-custom-id=\"nFGS1V4UgsTg\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"grbHKvy5_a4E\">\n<div data-brz-translate-text=\"1\">\n<h4 data-uniq-id=\"fTko1\" data-generated-css=\"brz-css-iWtdd\" class=\"brz-tp-lg-heading4 brz-css-qGgf7\"><strong style=\"color: rgb(0, 0, 0);\">Excel B\u00e1sico. <\/strong><\/h4>\n<h4 class=\"brz-tp-lg-heading4 brz-css-zlmGi\" data-uniq-id=\"fTko1\" data-generated-css=\"brz-css-iWtdd\"><strong style=\"color: rgb(0, 0, 0);\">60 Horas Constancia DC-3<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-ihJ6Q brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"jSyqHDEN_5ns\">\n<div data-brz-translate-text=\"1\">\n<p data-generated-css=\"brz-css-e3Eiq\" data-uniq-id=\"uuXVP\" class=\"brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-23 brz-fss-lg-px brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1_4 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-pH982\"><span style=\"color: rgb(0, 0, 0);\">Comenzar\u00e1s con la introducci\u00f3n de diferentes tipos de datos, ingresando tus primeras f\u00f3rmulas y mejorando la presentaci\u00f3n de las planillas para facilitar la interpretaci\u00f3n de la informaci\u00f3n.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-uRD2R\" data-brz-custom-id=\"ixuKj5lSxaYK\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"bnI5CYqzRc94\">\n<div data-brz-translate-text=\"1\">\n<h2 class=\"brz-lh-lg-1_3 brz-ls-lg-m_1_5 brz-fw-lg-700 brz-fss-lg-px brz-fs-lg-45 brz-ft-google brz-ff-overpass brz-tp-lg-empty brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-text-lg-center brz-css-jvtge\" data-uniq-id=\"zmUwJ\" data-generated-css=\"brz-css-qcXqL\"><span class=\"brz-cp-color7\" style=\"color: rgb(14, 113, 57);\">199 <\/span><\/h2>\n<h2 class=\"brz-text-lg-center brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-23 brz-fss-lg-px brz-fw-lg-700 brz-ls-lg-m_1_5 brz-lh-lg-1_3 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-cpCsk\" data-uniq-id=\"gJ4Dy\" data-generated-css=\"brz-css-vdcYB\"><span class=\"brz-cp-color7\" style=\"color: rgb(14, 113, 57);\">D\u00f3lares Americanos <\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"wcnb4i5N42c1\"><a class=\"brz-a brz-btn brz-css-tlaoB brz-css-ik_cZ\" href=\"https:\/\/miplataformaeducativa.com\/checkout.php?amount=azBhckpBUmN2RjF1T09VVWFlcnFxQT09OjqoLI6X2kCE4WRQ7DnIQFq5\" target=\"_blank\" rel=\"noopener\" data-brz-link-type=\"external\" id=\"modal-cupones\" data-brz-custom-id=\"wcnb4i5N42c1\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xml:space=\"preserve\" viewbox=\"0 0 24 24\" class=\"brz-icon-svg align-[initial] brz-css-y5e1q\" data-type=\"glyph\" data-name=\"tail-right\"><path fill=\"currentColor\" d=\"M22.707 11.293 15 3.586 13.586 5l6 6H2a1 1 0 1 0 0 2h17.586l-6 6L15 20.414l7.707-7.707a.999.999 0 0 0 0-1.414z\" class=\"nc-icon-wrapper\"\/><\/svg><span data-brz-translate-text=\"1\" class=\"brz-span brz-text__editor\" contenteditable=\"false\">Pagar Ahora<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-line brz-line-default brz-css-d1OIq brz-css-dDbTH\" data-brz-custom-id=\"p3R8L4AZX66M\">\n<hr class=\"brz-hr\"><\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"lt8q00p9CQC0\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-jKyob\" data-brz-custom-id=\"eqOvZsMPzBQr\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"mueOMBdjdcNn\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-dX3Wo\" data-brz-custom-id=\"ggKamSrzGCqR\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-image brz-css-sPvnA\" data-brz-custom-id=\"jxlXUxmnqtds\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-nCiTw brz-css-tqMdH\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/avanzado-1.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/avanzado-1.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/avanzado-1.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/avanzado-1.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/avanzado-1.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/avanzado-1.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/avanzado-1.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-z3ewA\" data-brz-custom-id=\"qojVSK_Aveul\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"woWJEYrZ8WuF\">\n<div data-brz-translate-text=\"1\">\n<h4 data-generated-css=\"brz-css-uARMO\" data-uniq-id=\"rQjgN\" class=\"brz-tp-lg-heading4 brz-css-eIEJ2\"><strong style=\"color: rgb(0, 0, 0);\">Excel Avanzado. <\/strong><\/h4>\n<h4 class=\"brz-tp-lg-heading4 brz-css-dgnsA\" data-generated-css=\"brz-css-uARMO\" data-uniq-id=\"rQjgN\"><strong style=\"color: rgb(0, 0, 0);\">60 Horas Constancia DC-3<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-tFb2v brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"lSGSGQskm7xP\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-fss-lg-px brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1_4 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-23 brz-css-f1kr6\" data-generated-css=\"brz-css-f9NB4\" data-uniq-id=\"cW64m\"><span style=\"color: rgb(0, 0, 0);\">Ser\u00e1s capaz de a\u00f1adirle funcionalidades que te ayudar\u00e1n a reducir el tiempo de trabajo, resolver problemas m\u00e1s complicados, aprender\u00e1s a realizar reportes en segundos y con la ayuda de la grabadora de macros te introducir\u00e1s al mundo de la programaci\u00f3n para automatizar tareas repetitivas.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-gzMB2\" data-brz-custom-id=\"ygEBu6UfI21c\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"rF3Jb1B_pR3W\">\n<div data-brz-translate-text=\"1\">\n<h2 class=\"brz-text-lg-center brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-45 brz-fss-lg-px brz-fw-lg-700 brz-ls-lg-m_1_5 brz-lh-lg-1_3 brz-css-zVsf4\" data-generated-css=\"brz-css-zmwt9\" data-uniq-id=\"rKJmC\"><span class=\"brz-cp-color7\" style=\"color: rgb(14, 113, 57);\">$299 <\/span><\/h2>\n<h2 class=\"brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-lh-lg-1_3 brz-ls-lg-m_1_5 brz-fw-lg-700 brz-fss-lg-px brz-fs-lg-23 brz-ft-google brz-ff-overpass brz-tp-lg-empty brz-text-lg-center brz-css-a2YkD\" data-generated-css=\"brz-css-pCrrK\" data-uniq-id=\"b8K3E\"><span class=\"brz-cp-color7\" style=\"color: rgb(14, 113, 57);\">D\u00f3lares Americanos <\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"jzBC2h2N6FGJ\"><a class=\"brz-a brz-btn brz-css-tlaoB brz-css-ezMHM\" href=\"https:\/\/miplataformaeducativa.com\/checkout.php?amount=SEc4TWd6R2NQZG1oRjE5SXgzRVUydz09OjrMhXLeHYRjo58axVDLJsAz\" target=\"_blank\" rel=\"noopener\" data-brz-link-type=\"external\" id=\"modal-cupones\" data-brz-custom-id=\"jzBC2h2N6FGJ\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xml:space=\"preserve\" viewbox=\"0 0 24 24\" class=\"brz-icon-svg align-[initial] brz-css-y5e1q\" data-type=\"glyph\" data-name=\"tail-right\"><path fill=\"currentColor\" d=\"M22.707 11.293 15 3.586 13.586 5l6 6H2a1 1 0 1 0 0 2h17.586l-6 6L15 20.414l7.707-7.707a.999.999 0 0 0 0-1.414z\" class=\"nc-icon-wrapper\"\/><\/svg><span data-brz-translate-text=\"1\" class=\"brz-span brz-text__editor\" contenteditable=\"false\">Pagar Ahora<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-line brz-line-default brz-css-d1OIq brz-css-bxw3S\" data-brz-custom-id=\"xVgpR_B6dDtR\">\n<hr class=\"brz-hr\"><\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"bYsD4xcXxdoS\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-pC8sj\" data-brz-custom-id=\"weEck1Eyoj28\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"uPySEm0yHMBi\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-bQbBs\" data-brz-custom-id=\"yROYOR80ZZDA\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-image brz-css-wbkeU\" data-brz-custom-id=\"o4cYubH8_YP9\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-qeaxZ brz-css-eq8N1\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/vba.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/vba.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/vba.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/vba.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/vba.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/vba.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/09\/vba.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-j_Hlu\" data-brz-custom-id=\"o8XAMCxnRR74\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"a_RL7vgZ_fBp\">\n<div data-brz-translate-text=\"1\">\n<h4 data-uniq-id=\"uHcwZ\" data-generated-css=\"brz-css-yVtOS\" class=\"brz-tp-lg-heading4 brz-css-cIkLH\"><strong style=\"color: rgb(0, 0, 0);\">Visual Basic Excel. <\/strong><\/h4>\n<h4 class=\"brz-tp-lg-heading4 brz-css-q9RY_\" data-uniq-id=\"uHcwZ\" data-generated-css=\"brz-css-yVtOS\"><strong style=\"color: rgb(0, 0, 0);\">90 Horas Constancia DC-3<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-e67ui brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"fqiGTM_62rf_\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-fss-lg-px brz-fw-lg-400 brz-ls-lg-0 brz-lh-lg-1_4 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-23 brz-css-hJBbN\" data-generated-css=\"brz-css-zjpse\" data-uniq-id=\"gQZZR\"><span style=\"color: rgb(0, 0, 0);\">Comenzar\u00e1s con la introducci\u00f3n de diferentes tipos de datos, ingresando tus primeras f\u00f3rmulas y mejorando la presentaci\u00f3n de las planillas para facilitar la interpretaci\u00f3n de la informaci\u00f3n.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-x3CGD\" data-brz-custom-id=\"is4uAiF4jcfs\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"yKDzJkJqP1Y7\">\n<div data-brz-translate-text=\"1\">\n<h2 class=\"brz-text-lg-center brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-45 brz-fss-lg-px brz-fw-lg-700 brz-ls-lg-m_1_5 brz-lh-lg-1_3 brz-css-m9UFn\" data-generated-css=\"brz-css-os2Uz\" data-uniq-id=\"dPtXv\"><span class=\"brz-cp-color7\" style=\"color: rgb(14, 113, 57);\">$399<\/span><\/h2>\n<h2 class=\"brz-fsft-lg-0 brz-fwdth-lg-100 brz-vfw-lg-400 brz-lh-lg-1_3 brz-ls-lg-m_1_5 brz-fw-lg-700 brz-fss-lg-px brz-fs-lg-23 brz-ft-google brz-ff-overpass brz-tp-lg-empty brz-text-lg-center brz-css-nAmVv\" data-generated-css=\"brz-css-z2VGh\" data-uniq-id=\"tpHYl\"><span class=\"brz-cp-color7\" style=\"color: rgb(14, 113, 57);\">D\u00f3lares Americanos <\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"sZz5KIEre6Td\"><a class=\"brz-a brz-btn brz-css-tlaoB brz-css-lAQqc\" href=\"https:\/\/miplataformaeducativa.com\/checkout.php?amount=azBhckpBUmN2RjF1T09VVWFlcnFxQT09OjqoLI6X2kCE4WRQ7DnIQFq5\" target=\"_blank\" rel=\"noopener\" data-brz-link-type=\"external\" id=\"modal-cupones\" data-brz-custom-id=\"sZz5KIEre6Td\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xml:space=\"preserve\" viewbox=\"0 0 24 24\" class=\"brz-icon-svg align-[initial] brz-css-y5e1q\" data-type=\"glyph\" data-name=\"tail-right\"><path fill=\"currentColor\" d=\"M22.707 11.293 15 3.586 13.586 5l6 6H2a1 1 0 1 0 0 2h17.586l-6 6L15 20.414l7.707-7.707a.999.999 0 0 0 0-1.414z\" class=\"nc-icon-wrapper\"\/><\/svg><span data-brz-translate-text=\"1\" class=\"brz-span brz-text__editor\" contenteditable=\"false\">Pagar Ahora<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"contacto\" data-brz-iteration-count=\"1\" class=\"brz-section brz-css-e8Aec brz-animated brz-css-vJLbH brz-css-ggNHJ\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-uRZOh\" data-brz-custom-id=\"qRmHsEgZqpPs\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"eOzEpJQklEem\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-css-hfiYJ brz-css-x1Qiu\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-fH_al\" data-brz-custom-id=\"xzoFZgLOUW4O\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-css-dVi2u brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"ncPE8e_rTjX9\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-22 brz-fss-lg-px brz-fw-lg-800 brz-ls-lg-0 brz-lh-lg-1_9 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-agefm\" data-generated-css=\"brz-css-e3Sly\" data-uniq-id=\"utdxP\"><strong class=\"brz-cp-color8\" style=\"color: rgba(var(--brz-global-color8),1);\">Contacto<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"zcpu6Xi3MTVn\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-vtRmp\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-nW8EE\" data-brz-custom-id=\"dxRHU_o_lZEG\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-pu33O\">\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"ru6U3FsKX3HT\">\n<div class=\"brz-icon__container\" data-brz-custom-id=\"ru6U3FsKX3HT\"><span class=\"brz-icon brz-span brz-css-sbUKi brz-css-vXctB\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\" class=\"brz-icon-svg align-[initial]\" data-type=\"fa\" data-name=\"map-marker-alt\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-suq6d\" data-brz-custom-id=\"kuINpEo1WNfN\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"rzFdNPYnx2Hw\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-tp-lg-paragraph brz-css-xUIj3\" data-generated-css=\"brz-css-fB6xy\" data-uniq-id=\"uuP6U\"><span style=\"color: white;\" class=\"brz-cp-color8\">Jalisco \u2013 M\u00e9xico<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"vYdRV2M8gYX6\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ brz-css-agxiT\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-fjQsN\" data-brz-custom-id=\"bVh1w0QGHkV8\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9 brz-css-lxdk2\">\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"q5HuC2306Miz\">\n<div class=\"brz-icon__container\" data-brz-custom-id=\"q5HuC2306Miz\"><span class=\"brz-icon brz-span brz-css-sbUKi brz-css-vHg8a\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" class=\"brz-icon-svg align-[initial]\" data-type=\"fa\" data-name=\"whatsapp\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-rmbiA\" data-brz-custom-id=\"bHB8VICVYS55\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"rrMEOIMryO_m\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-tp-lg-paragraph brz-css-wpwPj\" data-generated-css=\"brz-css-fB6xy\" data-uniq-id=\"uuP6U\"><span style=\"color: rgba(var(--brz-global-color8),1);\" class=\"brz-cp-color8\">WhatsApp: +52 33 2290 0505<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-image brz-css-kIrZS\" data-brz-custom-id=\"xvCOnTUxJe6E\"><picture class=\"brz-picture brz-d-block brz-p-relative brz-css-oWwOV brz-css-aY1dC\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/06\/logo-hmc-actual.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/06\/logo-hmc-actual.png 2x\" media=\"(min-width: 992px)\"><source srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/06\/logo-hmc-actual.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/06\/logo-hmc-actual.png 2x\" media=\"(min-width: 768px)\"><img decoding=\"async\" class=\"brz-img\" srcset=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/06\/logo-hmc-actual.png 1x, https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/06\/logo-hmc-actual.png 2x\" src=\"https:\/\/miplataformaeducativa.com\/es\/wp-content\/uploads\/2024\/06\/logo-hmc-actual.png\" alt=\"\" draggable=\"false\" loading=\"lazy\"><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-tLcNr\" data-brz-custom-id=\"oY9jXE6Avn3z\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"pumaLJmvA_xh\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-text-lg-center brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-23 brz-fss-lg-px brz-fw-lg-800 brz-ls-lg-0 brz-lh-lg-1_9 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-iENUu\" data-uniq-id=\"fmDFH\" data-generated-css=\"brz-css-uyUmX\"><strong style=\"color: white;\">Men\u00fa del Sitio<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-qlsJc brz-wrapper\">\n<div class=\"brz-menu-simple brz-css-wbADt brz-css-s6LQo\">\n<div style=\"min-height:20px\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-xOjB8\" data-brz-custom-id=\"bdRFERYPXurF\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div class=\"brz-wrapper-clone brz-css-wzZ2F brz-css-uOsY8\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5 brz-css-uqAWP\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"j9v_TkzdXWuT\"><a class=\"brz-a brz-btn brz-css-tlaoB brz-css-uQVuy\" href=\"#wow-modal-id-2\" target=\"_self\" rel=\"noopener\" data-brz-link-type=\"external\" data-brz-custom-id=\"j9v_TkzdXWuT\"><span data-brz-translate-text=\"1\" class=\"brz-span brz-text__editor\" contenteditable=\"false\">Proceso de Compra Tarifas Cambios Reembolsos<br \/>\n<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"brz-wrapper-clone brz-css-wzZ2F brz-css-lEtcz\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5 brz-css-ei9AY\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"zDA_1kDAFLNw\"><a class=\"brz-a brz-btn brz-css-tlaoB brz-css-eNDiU\" href=\"#wow-modal-id-3\" target=\"_self\" rel=\"noopener\" data-brz-link-type=\"external\" data-brz-custom-id=\"zDA_1kDAFLNw\"><span data-brz-translate-text=\"1\" class=\"brz-span brz-text__editor\" contenteditable=\"false\">T\u00e9rminos y Condiciones de uso<\/p>\n<p><\/span><\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"brz-wrapper-clone brz-css-wzZ2F brz-css-emka_\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5 brz-css-nsVyP\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"rpIqWGCPtzFV\"><a class=\"brz-a brz-btn brz-css-tlaoB brz-css-myAP5\" href=\"#wow-modal-id-1\" target=\"_self\" rel=\"noopener\" data-brz-link-type=\"external\" data-brz-custom-id=\"rpIqWGCPtzFV\"><span data-brz-translate-text=\"1\" class=\"brz-span brz-text__editor\" contenteditable=\"false\">Aviso de privacidad<\/p>\n<p><\/span><\/a><\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-wrapper\">\n<div class=\"brz-rich-text brz-rich-text__custom brz-css-fmws3\" data-brz-custom-id=\"zvHh6ITyQNE3\">\n<div data-brz-translate-text=\"1\">\n<p class=\"brz-text-lg-center brz-tp-lg-empty brz-ff-overpass brz-ft-google brz-fs-lg-22 brz-fss-lg-px brz-fw-lg-800 brz-ls-lg-0 brz-lh-lg-1_9 brz-vfw-lg-400 brz-fwdth-lg-100 brz-fsft-lg-0 brz-css-gQnsF\" data-uniq-id=\"nYIan\" data-generated-css=\"brz-css-ni5MS\"><strong class=\"brz-cp-color8\" style=\"color: white;\">S\u00edguenos<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-row__container brz-css-mEL63\" data-brz-custom-id=\"iwyfiPykzvhB\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-row brz-row--inner brz-css-hfiYJ\">\n<div class=\"brz-columns brz-css-ed7wV brz-css-z9p1F\" data-brz-custom-id=\"tQ4PiF_fRceo\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"rXgwcOZ33fdw\">\n<div class=\"brz-icon__container\" data-brz-custom-id=\"rXgwcOZ33fdw\"><a class=\"brz-a\" href=\"https:\/\/www.facebook.com\/profile.php?id=100065685571589\" target=\"_blank\" rel=\"noopener\" data-brz-link-type=\"external\"><span class=\"brz-icon brz-span brz-css-sbUKi brz-css-j7qln\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" class=\"brz-icon-svg align-[initial]\" data-type=\"fa\" data-name=\"facebook-square\"><path d=\"M400 32H48A48 48 0 0 0 0 80v352a48 48 0 0 0 48 48h137.25V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.27c-30.81 0-40.42 19.12-40.42 38.73V256h68.78l-11 71.69h-57.78V480H400a48 48 0 0 0 48-48V80a48 48 0 0 0-48-48z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-baX3_\" data-brz-custom-id=\"z3E__poNRUUX\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"e6y8RmE8LB0b\">\n<div class=\"brz-icon__container\" data-brz-custom-id=\"e6y8RmE8LB0b\"><a class=\"brz-a\" href=\"https:\/\/www.instagram.com\/miplataformaedu\/\" target=\"_blank\" rel=\"noopener\" data-brz-link-type=\"external\"><span class=\"brz-icon brz-span brz-css-sbUKi brz-css-eljwD\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" class=\"brz-icon-svg align-[initial]\" data-type=\"fa\" data-name=\"instagram\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brz-columns brz-css-ed7wV brz-css-jA0ci\" data-brz-custom-id=\"bpT1yQBojWV2\">\n<div class=\"brz-bg\"><\/div>\n<div class=\"brz-column__items brz-css-hi8w9\">\n<div class=\"brz-wrapper-clone brz-css-wzZ2F\">\n<div class=\"brz-d-xs-flex brz-flex-xs-wrap brz-css-r8tL5\" data-brz-custom-id>\n<div class=\"brz-wrapper-clone__item\" id=\"dM1ePK2KYP38\">\n<div class=\"brz-icon__container\" data-brz-custom-id=\"dM1ePK2KYP38\"><a class=\"brz-a\" href=\"https:\/\/www.tiktok.com\/@miplataformaeducativa?_t=8nLBLiXyx2k&amp;_r=1\" target=\"_blank\" rel=\"noopener\" data-brz-link-type=\"external\"><span class=\"brz-icon brz-span brz-css-sbUKi brz-css-vejBd\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\" class=\"brz-icon-svg align-[initial]\" data-type=\"fa\" data-name=\"tiktok\"><!--! Font Awesome Free 6.4.0 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc.--><path d=\"M448 209.91a210.06 210.06 0 0 1-122.77-39.25v178.72A162.55 162.55 0 1 1 185 188.31v89.89a74.62 74.62 0 1 0 52.23 71.18V0h88a121.18 121.18 0 0 0 1.86 22.17A122.18 122.18 0 0 0 381 102.39a121.43 121.43 0 0 0 67 20.14Z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"ptPK3oUvw38n\" class=\"brz-section brz-css-e8Aec\">\n<div class=\"brz-section__content brz-section--boxed brz-css-w4d24 brz-css-hv0FK\" data-brz-custom-id=\"lImlZmeCQeBb\">\n<div class=\"brz-bg\">\n<div class=\"brz-bg-color\"><\/div>\n<\/div>\n<div class=\"brz-container brz-css-fH4YD\">\n<div id class=\"brz-css-zwtwv brz-css-lIgh2 brz-wrapper\">\n<div class=\"brz-wp-shortcode brz-css-kqska\" data-brz-custom-id=\"iBWuscg0G8IX\">\n<div><div class=\"modal-window\" id=\"modal-window-1\"><div class=\"modal-window__wrapper\"><div class=\"modal-window__content\"><div class=\"modal-window__close\">Cerrar<\/div><div class=\"modal-window__content-wrapper\"><div class=\"modal-window__content-main\"><p>El presente Aviso se emite en cumplimiento a las disposiciones aplicables de la Ley Federal de Protecci\u00f3n de Datos personales en posesi\u00f3n de los Particulares (\u201cLey de Datos Personales\u201d). 1. Identidad y domicilio del Responsable. La persona y\/o plataforma responsable de recabar Datos Personales es la denominada <strong>MI PLATAFORMA EDUCATIVA<\/strong>, es una PLATAFORMA mexicana que presta los servicios de edici\u00f3n y publicaci\u00f3n de cursos en l\u00ednea y cualquier tipo de contenido relacionado con las \u00e1reas de negocios, industriales, comerciales, empresariales, culturales, cient\u00edficas y tecnol\u00f3gicas, la explotaci\u00f3n de material literario bajo cualquier figura jur\u00eddica, en diversas plataformas electr\u00f3nicas, entre otras actividades. Para efectos del cumplimiento a lo se\u00f1alado en el art\u00edculo 16 fracci\u00f3n I de la Ley de Datos Personales tiene su domicilio ubicado en Frederick Chopin 5150, Colonia La Estancia, CP 45030, Zapopan, Jalisco. El departamento responsable de datos personales, quien dar\u00e1 tr\u00e1mite a las solicitudes de los titulares o para el ejercicio de los derechos ARCO (\u201cacceso, rectificaci\u00f3n, cancelaci\u00f3n, oposici\u00f3n\u201d) que se\u00f1ala la Ley, es SERVICIO AL CLIENTE, quien se encuentra ubicada en el mismo domicilio arriba citado, quien seguir\u00e1 el procedimiento se\u00f1alado en el numeral 5 del presente Aviso de Privacidad. 2. Finalidad del Tratamiento de los Datos Personales. <strong>MI PLATAFORMA EDUCATIVA<\/strong> recabar\u00e1 del Titular de los Datos Personales y\/o los Datos Personales Sensibles, para la identificaci\u00f3n de los usuarios, entendiendo por usuario, aquella persona f\u00edsica que lleve a cabo la compra de material, servicio o contenido, mismo que pone en venta <strong>MI PLATAFORMA EDUCATIVA<\/strong>. En este sentido, <strong>MI PLATAFORMA EDUCATIVA<\/strong> recabar\u00e1 del Titular de los Datos Personales y\/o los Datos Personales Sensibles, para las siguientes finalidades: Finalidades principales: * Para la celebraci\u00f3n del contrato de compraventa de los Productos celebrado entre <strong>MI PLATAFORMA EDUCATIVA<\/strong> y el Titular de los Datos Personales y\/o Datos Personales Sensibles. * Brindar un mejor servicio. * Se le otorgue alguna promoci\u00f3n de alg\u00fan servicio que se encuentre disponible. * Para solicitar a una sociedad de informaci\u00f3n crediticia un reporte de cr\u00e9dito y\/o reporte de cr\u00e9dito especial del Titular de los Datos Personales y\/o Datos Personales Sensibles con base a la ley para regular las sociedades de informaci\u00f3n crediticia, mediante el cual se obtenga el historial crediticio del Titular antes se\u00f1alado. Finalidades secundarias: * Fines mercadot\u00e9cnicos, publicitarios o prospecci\u00f3n comercial. * Enviar correo electr\u00f3nico a soporte@hoymecapacito.com en caso de que no desee que sus datos personales sean tratados para las finalidades secundarias. 3. Definiciones, y en su caso aceptaci\u00f3n expresa. Se define en t\u00e9rminos de la Ley de Datos Personales, los siguientes t\u00e9rminos: Datos Personales: Cualquier informaci\u00f3n concerniente a una persona f\u00edsica identificada o identificable, incluyendo de manera enunciativa m\u00e1s no limitativa: (i) nombre completo, (ii) edad o fecha de nacimiento, (iii) lugar de nacimiento, (iv) actividad, profesi\u00f3n, ocupaci\u00f3n u oficio (v) domicilio particular, (vi) n\u00famero telef\u00f3nico, (vii) correo electr\u00f3nico, entre otros. Datos Personales Sensibles: son aquellos que puedan revelar aspectos como origen racial o \u00e9tnico, estado de salud presente y futuro, informaci\u00f3n gen\u00e9tica, creencias religiosas, filos\u00f3ficas y morales, afiliaci\u00f3n sindical, opiniones pol\u00edticas, preferencia sexual, entre otros que puedan causar discriminaci\u00f3n o da\u00f1o. Datos Patrimoniales: Informaci\u00f3n concerniente a una persona f\u00edsica relativa a sus bienes, derechos, cargas u obligaciones susceptibles de valoraci\u00f3n econ\u00f3mica, como pueden ser: bienes muebles e inmuebles; informaci\u00f3n fiscal; historial crediticio; ingresos y egresos; cuentas bancarias; seguros; afores; fianzas, n\u00famero de tarjeta de cr\u00e9dito, n\u00famero de seguridad, entre otros. En relaci\u00f3n a los Datos Personales sensibles y\/o Datos patrimoniales o financieros, otorgo mi consentimiento para que los citados datos sean tratados conforme a lo se\u00f1alado en el presente Aviso de Privacidad. Es importante hacerle saber, que en el caso de la negativa por parte de usted hacia <strong>MI PLATAFORMA EDUCATIVA<\/strong> respecto al tratamiento de datos personales, implica una imposibilidad por parte de <strong>MI PLATAFORMA EDUCATIVA<\/strong> en celebrar el contrato de compraventa de los Productos respectivo. Los datos que usted como titular proporcione ser\u00e1n tratados bajo los principios establecidos en la Ley de Datos Personales (licitud, consentimiento, informaci\u00f3n, calidad, finalidad, lealtad, proporcionalidad y responsabilidad). 4. Derechos para limitar el uso o divulgaci\u00f3n de los Datos Personales. Usted podr\u00e1 limitar el uso o la divulgaci\u00f3n de sus datos personales enviando su solicitud a nuestro Departamento de Protecci\u00f3n de Datos Personales, mediante el procedimiento se\u00f1alado en el numeral 5 del presente Aviso de Privacidad. Los requisitos para acreditar su identidad y el procedimiento se realizar\u00e1n con base a los requisitos se\u00f1alados en el numeral siguiente. En caso de que su solicitud sea procedente, <strong>MI PLATAFORMA EDUCATIVA<\/strong>, lo registrar\u00e1 en el listado de exclusi\u00f3n correspondiente.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-aWOSZ brz-wrapper\">\n<div class=\"brz-wp-shortcode brz-css-kqska\" data-brz-custom-id=\"hkz2g2mz_9qV\">\n<div><div class=\"modal-window\" id=\"modal-window-2\"><div class=\"modal-window__wrapper\"><div class=\"modal-window__content\"><div class=\"modal-window__close\">Cerrar<\/div><div class=\"modal-window__content-wrapper\"><div class=\"modal-window__content-main\"><p><strong>TARIFAS<\/strong><\/p>\r\n<p>Para utilizar los cursos en l\u00ednea y otros Servicios que <strong>MI PLATAFORMA EDUCATIVA<\/strong> ofrece es necesario pagar una tarifa. Acepta pagar las tarifas del contenido que compre y autoriza a <strong>MI PLATAFORMA EDUCATIVA<\/strong> a cobrarle los Servicios con el m\u00e9todo de pago que seleccione. Las tarifas se cobrar\u00e1n tanto si utiliza los Servicios comprados como si no. Es responsable de pagar puntualmente todas las tarifas que <strong>MI PLATAFORMA EDUCATIVA<\/strong> cobre, as\u00ed como los impuestos aplicables. Nos reservamos el derecho de inhabilitar o retirar el acceso a cualquier contenido por el que no hayamos recibido un pago adecuado. Las tarifas pueden variar seg\u00fan su ubicaci\u00f3n y otros factores. Si tiene la sesi\u00f3n iniciada en su cuenta, la moneda que ver\u00e1 seleccionada se basar\u00e1 en su ubicaci\u00f3n en el momento de crear la cuenta. No obstante, las tarifas finales que le cobremos se calcular\u00e1n siempre en pesos mexicanos. Ocasionalmente, realizamos promociones y rebajas para nuestro contenido, en las que determinado contenido est\u00e1 disponible a precios con descuento durante cierto per\u00edodo de tiempo. El precio aplicable al contenido ser\u00e1 el precio en el momento en el que compr\u00f3 el contenido. Proporcionar\u00e1 a <strong>MI PLATAFORMA EDUCATIVA<\/strong> informaci\u00f3n sobre su tarjeta de cr\u00e9dito u otro instrumento de pago. Declara y garantiza que (a) esta informaci\u00f3n es veraz, exacta, actual y completa, y que est\u00e1 autorizado a utilizar este instrumento de pago, y (b) mantendr\u00e1 y actualizar\u00e1 puntualmente esta informaci\u00f3n para que siga siendo veraz, exacta, actual y completa. Acepta que <strong>MI PLATAFORMA EDUCATIVA<\/strong> puede actualizar sus m\u00e9todos de pago con la informaci\u00f3n que nuestros proveedores de servicios de pago nos proporcionen y nos autoriza a seguir cobrando las tarifas vigentes en su m\u00e9todo de pago actualizado. <strong>MI PLATAFORMA EDUCATIVA<\/strong> se reserva el derecho, en cualquier momento, de cambiar cualquier tarifa o de comenzar a cobrar cualquier Servicio hasta entonces gratuito, seg\u00fan su propio criterio exclusivo. Cualquier cambio, actualizaci\u00f3n o modificaci\u00f3n ser\u00e1 efectivo inmediatamente al publicarlo a trav\u00e9s de los Servicios pertinentes (estos cambios no se aplicar\u00e1n a las tarifas pagadas antes de realizarlos). Tenga en cuenta que debido a los sistemas de precios de los proveedores de plataformas m\u00f3viles y de sus pol\u00edticas, es posible que, en ocasiones, el precio del contenido ofrecido en el sitio web de <strong>MI PLATAFORMA EDUCATIVA<\/strong> no sea el mismo que el precio ofrecido en nuestras aplicaciones m\u00f3viles. <strong>REEMBOLSOS. <\/strong>Tenga en cuenta que nuestra pol\u00edtica de reembolsos distingue entre los pagos \u00fanicos para los cursos: (i) Los reembolsos no est\u00e1n disponibles para las cuentas que infrinjan estas Condiciones de uso o que, seg\u00fan el criterio exclusivo y absoluto de <strong>MI PLATAFORMA EDUCATIVA<\/strong>, sean inaceptables por cualquier otro motivo; (ii) si <strong>MI PLATAFORMA EDUCATIVA<\/strong> determina que usted hace un uso inadecuado de nuestra pol\u00edtica de reembolsos, nos reservamos el derecho de suspender o rescindir su cuenta y de denegar o restringir cualquier uso actual o futuro del Servicio sin realizar ning\u00fan reembolso; (iii) para solicitar un reembolso, contacte con nosotros a trav\u00e9s de nuestro\u00a0correo electr\u00f3nico soporte@mipltaformaeducativa.com; (iv) <strong>MI PLATAFORMA EDUCATIVA<\/strong> aplicar\u00e1 su reembolso a su m\u00e9todo de pago original; (v) lamentablemente, en este momento, no podemos ofrecer reembolsos parciales para sus compras. Si dentro de los primeros 14 d\u00edas despu\u00e9s de comprar un curso no est\u00e1 conforme con dicho curso, <strong>MI PLATAFORMA EDUCATIVA<\/strong> le reembolsar\u00e1 el importe completo de su compra y rescindir\u00e1 posteriormente su acceso al curso. No podremos realizar ning\u00fan reembolso solicitado despu\u00e9s de este per\u00edodo de 14 d\u00edas.<br \/><br \/><\/p>\r\n<p><strong>Cambios y Reembolsos<\/strong><\/p>\r\n<p>En este art\u00edculo te explicamos c\u00f3mo proceder con un cambio o una devoluci\u00f3n de un curso que has adquirido recientemente.\u00a0 <strong>MI PLATAFORMA EDUCATIVA<\/strong> se reserva el derecho, de limitar, otorgar o denegar las solicitudes de reembolso en los casos en que consideremos que hay un abuso de nuestras pol\u00edticas.\u00a0\u00bfC\u00f3mo puedo pedir el reembolso de mi pedido? Puedes solicitar el reembolso de tu pedido, siempre que se encuentre dentro del plazo de\u00a07 d\u00edas posteriores al momento de la compra.\u00a0*Toma en cuenta que cursos que hayas canjeado como regalo no pueden reembolsarse, pues esa acci\u00f3n solo podr\u00e1 hacerla el comprador. Si has canjeado tu c\u00f3digo de regalo por un curso err\u00f3neo puedes env\u00edanos\u00a0al correo electr\u00f3nico <a href=\"mailto:soporte@miplataformaeducativa.com\">soporte@miplataformaeducativa.com<\/a> la solicitud de cambio de curso.\u00a0Compras realizadas con Tarjeta \/ Paypal (a trav\u00e9s de la web). Env\u00edanos\u00a0al correo electr\u00f3nico <a href=\"mailto:soporte@miplataformaeducativa.com\">soporte@miplataformaeducativa.com<\/a> la solicitud de reembolso. El reembolso se har\u00e1 a la misma tarjeta\/cuenta de PayPal con la que se realiz\u00f3 el pago. Ten en cuenta que puede llevar varios d\u00edas en verse reflejado en tu estado de\u00a0 cuenta, dependiendo de los plazos de gesti\u00f3n de tu banco. M\u00e9todo de pago local o efectivo \/ transferencia (a trav\u00e9s de la web) Este m\u00e9todo de pago \u00fanicamente est\u00e1 disponible en M\u00e9xico. Si realizaste el pago en efectivo, por favor env\u00edanos\u00a0al correo electr\u00f3nico soporte@miplataformaeducativa.com, los datos que a continuaci\u00f3n te detallamos, ya que se tramitar\u00e1 mediante transferencia bancaria:\u00a0Nombre completo del beneficiario, N\u00famero de identificaci\u00f3n (No. de c\u00e9dula, CURP, CPF), N\u00famero de cuenta (CLABE interbancaria de 18 d\u00edgitos), Tipo de cuenta (de ahorros o corriente) y Nombre de tu entidad bancaria.\u00a0Ten en cuenta que, una vez efectuado puede llevar varios d\u00edas hasta ver el importe reflejado en tu estado de cuenta, dependiendo de los plazos de gesti\u00f3n de tu banco. \u00bfC\u00f3mo puedo solicitar un cambio de curso? Puedes solicitar un cambio de curso siempre que se encuentre dentro del plazo de\u00a07 d\u00edas desde el momento de la compra. Si has recibido un curso como\u00a0regalo, puedes solicitar el cambio de curso siempre que se encuentre dentro del plazo de\u00a07 d\u00edas\u00a0desde el momento de canje. Para realizar un cambio de curso, Env\u00edanos\u00a0al correo electr\u00f3nico <a href=\"mailto:soporte@miplataformaeducativa.com\">soporte@miplataformaeducativa.com<\/a> la solicitud de cambio de curso. A\u00f1ad\u00ed por error un curso m\u00e1s a mi pedido, \u00bfpuedo pedir un reembolso parcial? La pol\u00edtica de reembolso de <strong>MI PLATAFORMA EDUCATIVA<\/strong> no permite reembolsos parciales, sin embargo te ofrecemos las siguientes alternativas:\u00a0Si has comprado varios cursos en un mismo pedido: Proceder al\u00a0reembolso\u00a0total del pedido y volver a realizar la compra de forma correcta o Realizar un\u00a0cambio se curso\/s.\u00a0<\/p>\r\n<p><strong>Proceso de compra<\/strong><\/p>\r\n<p>M\u00e9todos de pago. En MI PLATAFORMA EDUCTIVA contamos con diferentes alternativas de m\u00e9todos de pago dependiendo de la ubicaci\u00f3n* en la que te encuentres, para que puedas completar tus compras de la manera en la que m\u00e1s te convenga. A continuaci\u00f3n te detallamos cada una de ellas: Pago con tarjeta de cr\u00e9dito\/d\u00e9bito, Pago con PayPal y Pago con Efectivo y otros m\u00e9todos de pago. Solicite la forma de pago al correo electr\u00f3nico <a href=\"mailto:soporte@miplataformaeducativa.com\">soporte@miplataformaeducativa.com<\/a> y le enviaremos los pasos a seguir para realizar el pago. \u00bfEn qu\u00e9 moneda obtendr\u00e9 mi factura? Cuando realizas una compra te enviamos el correspondiente recibo de pago en moneda local. No obstante, si deseas obtener tu factura, \u00e9sta aparecer\u00e1 en\u00a0pesos mexicanos, de acuerdo a la moneda en la que se realiza el cobro. \u00bfC\u00f3mo puedo obtener la factura de mi compra? Cuando realizas una compra en <strong>MI PLATAFORMA EDUCATIVA<\/strong> env\u00eda al correo electr\u00f3nico <a href=\"mailto:soporte@miplataformaeducativa.com\">soporte@miplataformaeducativa.com<\/a> los datos fiscales para generar la factura.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<div id class=\"brz-css-zwtwv brz-css-cXU5K brz-wrapper\">\n<div class=\"brz-wp-shortcode brz-css-kqska\" data-brz-custom-id=\"fNcKfmciqolB\">\n<div><div class=\"modal-window\" id=\"modal-window-3\"><div class=\"modal-window__wrapper\"><div class=\"modal-window__content\"><div class=\"modal-window__close\">Cerrar<\/div><div class=\"modal-window__content-wrapper\"><div class=\"modal-window__content-main\"><p>Estas Condiciones de uso se actualizaron por \u00faltima vez el 23 de julio de 2026.<\/p>\r\n<ol>\r\n<li><strong> INTRODUCCI\u00d3N. 1.1. LE DAMOS LA BIENVENIDA A MI PLATAFORMA EDUCATIVA.\u00a0MI PLATAFORMA EDUCATIVA<\/strong>, le ofrece sus Servicios (tal como se describen a continuaci\u00f3n) a trav\u00e9s de su sitio web (<a href=\"http:\/\/www.miplataformaeducativa.com\/\">www.miplataformaeducativa.com<\/a>), de sus aplicaciones m\u00f3viles y de otras propiedades interactivas, que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>posee y opera, seg\u00fan las siguientes Condiciones de uso. El Sitio es una comunidad en l\u00ednea, donde los usuarios pueden acceder a los cursos que all\u00ed est\u00e1n disponibles, comprarlos. Los Servicios incluyen, entre otros, cualquier servicio o contenido que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>ponga a su disposici\u00f3n o realice para usted, as\u00ed como la oferta de cualquier material mostrado, transmitido o ejecutado en el Sitio.\u00a0<strong>1.2. INFORMACI\u00d3N DEL PRESTADOR DEL SERVICIO. <\/strong>Titular: HEVER RAUL GARCIA RODRIGUEZ. Tipo de contribuyente: Persona F\u00edsica. Registro Federal de Contribuyentes: GARH7603098Q7. Clave \u00danica de Registro de Poblaci\u00f3n: GARH760309HNERDV00. Domicilio fiscal: Frederick Chopin 5150, Colonia La Estancia, CP 45030, Zapopan, Jalisco, M\u00e9xico. Nombre comercial MI PLATAFORMA EDUCATIVA. Correo electr\u00f3nico de contacto: <a href=\"mailto:ventas@miplataformaeducativa.com\">ventas@miplataformaeducativa.com<\/a>. Tel\u00e9fono: +525514012812. Sitio web administrado por: HEVER RAUL GARCIA RODRIGUEZ, quien es el titular y responsable de la operaci\u00f3n, comercializaci\u00f3n y prestaci\u00f3n de los servicios ofrecidos a trav\u00e9s de este sitio web. <strong>2. ACEPTACI\u00d3N DE LAS CONDICIONES DE USO.\u00a0<\/strong>Estas Condiciones de uso se establecen por y entre usted y\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>. Las condiciones siguientes, junto con cualquier documento incorporado expresamente por referencia, regir\u00e1n su acceso a los Servicios, y el uso que haga de los mismos, tanto si lo hace como invitado o usuario registrado. Lea las Condiciones de uso detenidamente antes de comenzar a utilizar los Servicios. Al utilizar los Servicios y acceder al Sitio, acepta y acuerda estar obligado por estas Condiciones de uso y por nuestra Pol\u00edtica de privacidad (<u>Aviso de privacidad<\/u>), incorporada al presente documento por referencia, y cumplir los contenidos de ambos documentos. Si no est\u00e1 de acuerdo con estas Condiciones de uso, o con nuestra Pol\u00edtica de privacidad, salga inmediatamente de esta p\u00e1gina sin acceder a los Servicios ni utilizarlos. Si usa los Servicios en nombre de una empresa, dicha empresa tambi\u00e9n acepta estas Condiciones de uso.\u00a0<strong>1.3. CAMBIOS EN LAS CONDICIONES DE USO.\u00a0<\/strong>Podemos revisar y actualizar peri\u00f3dicamente estas Condiciones de uso seg\u00fan nuestro criterio exclusivo. Si cambiamos estas Condiciones de uso, en funci\u00f3n de la naturaleza de la modificaci\u00f3n, publicaremos los cambios en esta p\u00e1gina e indicaremos en su parte superior la fecha en la que estas Condiciones de uso se revisaron por \u00faltima vez o se lo notificaremos, ya sea a trav\u00e9s de la interfaz de usuario de los Servicios, en una notificaci\u00f3n por correo electr\u00f3nico o por otros medios razonables, y como requiera la legislaci\u00f3n vigente. Estos cambios ser\u00e1n efectivos no antes de catorce (14) d\u00edas despu\u00e9s de publicarse, salvo en el caso de los cambios realizados a causa de funciones nuevas de los Servicios o por motivos legales, que entrar\u00e1n en vigor inmediatamente. Si utiliza de manera continuada los Servicios una vez publicadas las Condiciones de uso revisadas, acepta los cambios y est\u00e1 de acuerdo con ellos. Se espera que revise peri\u00f3dicamente esta p\u00e1gina para estar al corriente de los cambios, puesto que est\u00e1 obligado a cumplirlos.\u00a0<strong>2. ACCESO A LOS SERVICIOS Y SEGURIDAD DE LA CUENTA. 2.1. ACCESO A LOS SERVICIOS.\u00a0MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se reserva el derecho de modificar o interrumpir, temporal o permanentemente, los Servicios (o cualquier parte de ellos) con o sin aviso previo. Acepta que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no ser\u00e1 responsable ante usted ni ante ning\u00fan tercero de cualquier modificaci\u00f3n, suspensi\u00f3n o interrupci\u00f3n de los Servicios. Tampoco seremos responsables de que, por cualquier motivo, los Servicios, ya sea en su totalidad o en parte, no est\u00e9n disponibles en cualquier momento o durante cualquier per\u00edodo. Ocasionalmente, podemos restringir el acceso a algunas partes de los Servicios, o a su totalidad, a los usuarios, incluidos los registrados. Nos reservamos el derecho de inhabilitar cualquier nombre de usuario, contrase\u00f1a u otro identificador, tanto si lo ha elegido usted o se lo hemos proporcionado, en cualquier momento, seg\u00fan nuestro criterio exclusivo, por cualquier motivo o sin raz\u00f3n alguna, incluido en el caso de que, en nuestra opini\u00f3n, haya infringido cualquier estipulaci\u00f3n de estas Condiciones de uso. Se puede acceder a los Servicios desde cualquier parte del mundo, pero esto no implica que todos los Servicios, o todas las caracter\u00edsticas de los Servicios, est\u00e1n disponibles en su pa\u00eds, o que las Contribuciones del usuario (tal como se definen a continuaci\u00f3n) disponibles a trav\u00e9s de los Servicios sean legales en su pa\u00eds.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0puede bloquear el acceso a determinados Servicios (o a caracter\u00edsticas o contenidos particulares de los Servicios) en ciertos pa\u00edses. Debe asegurarse de que el uso que haga de los Servicios sea legal en su pa\u00eds de residencia. Los Servicios no est\u00e1n disponibles en todos los idiomas. Los Servicios est\u00e1n disponibles solo para usuarios mayores de 16 a\u00f1os; si usted todav\u00eda no tiene la edad de consentimiento requerida para utilizar servicios en l\u00ednea en el lugar donde viva, no podr\u00e1 usarlos, pero le animamos a que invite a un progenitor o un tutor legal para que abra una cuenta y le ayude a acceder al contenido que sea apropiado para usted. Si todav\u00eda no tiene la edad de consentimiento para utilizar servicios en l\u00ednea, no debe acceder a los Servicios. Si descubrimos que ha creado una cuenta con la que se infringen estas normas, rescindiremos dicha cuenta.\u00a0<strong>2.2. REGISTRO.\u00a0<\/strong>Para acceder al Sitio o a algunos de los Servicios que ah\u00ed se ofrecen, es posible que le solicitemos que facilite ciertos datos de registro u otro tipo de informaci\u00f3n. Acepta: (a) proporcionar informaci\u00f3n sobre usted verdadera, exacta, actual y completa en el formulario de registro y (b) mantener y actualizar puntualmente esta informaci\u00f3n para que siga siendo verdadera, exacta, actual y completa. Si facilita cualquier informaci\u00f3n que no sea verdadera, exacta, actual y completa, o si\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0tiene fundamentos razonables para sospechar que dicha informaci\u00f3n no sea verdadera, exacta, actual y completa,\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0tiene el derecho de suspender o rescindir su cuenta y de denegarle el uso actual o futuro de los Servicios (o de cualquier parte de ellos). Acepta que toda la informaci\u00f3n que proporcione para registrarse en los Servicios o a trav\u00e9s de otras v\u00edas, incluido, entre otros, el uso de cualquier caracter\u00edstica interactiva, se regir\u00e1 por nuestro\u00a0<u>Aviso de privacidad<\/u>y consiente todas las acciones que llevemos a cabo con relaci\u00f3n a su informaci\u00f3n de acuerdo con nuestro\u00a0<u>Aviso de privacidad<\/u>.\u00a0<strong>2.3. SEGURIDAD DE LA CUENTA.\u00a0<\/strong>Si elige, o le proporcionamos, un nombre de usuario, una contrase\u00f1a o cualquier otro tipo de dato como parte de nuestros procedimientos de seguridad, debe tratar dicha informaci\u00f3n como confidencial y no debe revelarla a ninguna otra persona ni entidad. Tambi\u00e9n reconoce que su cuenta es personal para usted y acepta no facilitar a ninguna otra persona el acceso a los Servicios o a parte de ellos mediante su nombre de usuario, contrase\u00f1a u otra informaci\u00f3n de seguridad. Debe proteger sus credenciales de inicio de sesi\u00f3n; ser\u00e1 el responsable \u00fanico de todas las actividades que se lleven a cabo a trav\u00e9s de su cuenta. Acepta notificarnos inmediatamente de cualquier acceso o uso no autorizado relativo a su nombre de usuario o contrase\u00f1a o de cualquier otra vulneraci\u00f3n de seguridad. Tambi\u00e9n acepta asegurarse de que cerrar\u00e1 la sesi\u00f3n de su cuenta al final de cada sesi\u00f3n. Debe ser particularmente precavido al acceder a su cuenta desde un ordenador p\u00fablico o compartido para que otras personas no puedan ver o registrar su contrase\u00f1a u otra informaci\u00f3n personal.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no se responsabiliza de cualquier acci\u00f3n u omisi\u00f3n por su parte, incluidos los da\u00f1os de cualquier tipo producidos como resultado de dichas acciones u omisiones.\u00a0<strong>3. COMPORTAMIENTO DEL USUARIO. 3.1. USO DEL SERVICIO.\u00a0<\/strong>Le ofrecemos el Sitio y el Servicio \u00fanicamente para su uso personal y no comercial. Salvo que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0lo autorice expresamente por escrito, acepta no mostrar, distribuir, licenciar, ejecutar, publicar, reproducir, duplicar, copiar, crear trabajos derivados, modificar, vender, revender, explotar, transferir ni cargar con cualquier finalidad comercial cualquier parte del Servicio, el uso del Servicio ni el acceso al Servicio. El Servicio no se debe utilizar ni usar como medio para almacenar sus fotograf\u00edas, im\u00e1genes, v\u00eddeos, sonidos o cualquier otro contenido que cargue; debe conservar sus propias copias de todo el contenido publicado en el Sitio. No tenemos ninguna obligaci\u00f3n de conservar ning\u00fan contenido que haya publicado durante cualquier per\u00edodo de tiempo m\u00e1s all\u00e1 de lo que la legislaci\u00f3n vigente exija.\u00a0<strong>3.2. USOS PROHIBIDOS.\u00a0<\/strong>Por el presente documento, acepta no utilizar los Servicios con cualquier finalidad ilegal o que estas Condiciones de uso proh\u00edban, o con cualquier otra intenci\u00f3n que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no haya previsto razonablemente. \u00danicamente como ejemplo, sin limitaci\u00f3n, acepta no utilizar los Servicios: * De una manera que infrinja cualquier ley o normativa local, regional, nacional o internacional. * Para (o para intentar) maltratar, da\u00f1ar, acosar, amenazar, suplantar o intimidar a cualquier persona. * Para enviar, recibir intencionadamente, cargar, publicar, descargar, usar o reutilizar cualquier material o contenido que (i) contenga material ilegal, difamatorio, obsceno, indecente, abusivo, ofensivo, acosador, violento, detestable, provocador o inaceptable por cualquier otro motivo; (ii) promueva material sexualmente expl\u00edcito o pornogr\u00e1fico, violencia o discriminaci\u00f3n por raza, sexo, religi\u00f3n, nacionalidad, discapacidad, orientaci\u00f3n sexual o edad; (iii) infrinja cualquier patente, marca comercial, secreto comercial, derecho de autor u otros derechos de propiedad intelectual o de cualquier otro tipo de cualquier persona o entidad; (iv) vulnere los derechos legales (incluidos los derechos de publicidad y privacidad) de terceros o contenga cualquier material que pudiera crear cualquier responsabilidad civil o penal en virtud de la legislaci\u00f3n o las normativas vigentes o, por otros motivos, entrar en conflicto con estas Condiciones de uso; (v) probablemente enga\u00f1e a cualquier persona; (vi) promueva cualquier actividad ilegal, o proponga, promueva o favorezca cualquier acto il\u00edcito; (vii) irrite, moleste o cause una ansiedad innecesaria, o probablemente enoje, incomode, alarme o incordie a cualquier otra persona; (viii) suplante a cualquier persona o represente inadecuadamente su identidad o afiliaci\u00f3n con cualquier persona u organizaci\u00f3n; (ix) implique actividades u ofertas comerciales, como concursos, sorteos y otras promociones de ventas, canjes o campa\u00f1as publicitarias; (x) o d\u00e9 la impresi\u00f3n de que emana de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, o que la empresa o cualquier otra persona o entidad lo promociona, si este no es el caso.<\/li>\r\n<\/ol>\r\n<p>*Para transmitir o procurar el env\u00edo de cualquier material publicitario o promocional, incluidos el \u00abcorreo basura\u00bb, las \u00abcartas en cadena\u00bb, el \u00abcorreo no deseado\u00bb o cualquier otra solicitaci\u00f3n similar, ni para conseguir o recopilar direcciones de correo electr\u00f3nico u otra informaci\u00f3n de contacto de otros usuarios de los Servicios por medios electr\u00f3nicos u otros con la finalidad de enviar correos u otros tipos de comunicaci\u00f3n no solicitados. * Para suplantar o intentar suplantar a <strong>MI PLATAFORMA EDUCATIVA<\/strong>, a un empleado de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, a otro usuario o a cualquier otra persona o entidad (incluido, entre otros, el uso de direcciones de correo electr\u00f3nico o nombres de pantalla asociados a cualquiera de los anteriores), o para representar inadecuadamente su afiliaci\u00f3n con una persona o entidad. * Para crear m\u00faltiples cuenta con la finalidad de manipular (es decir, mediante votos \u00abMe gusta\u00bb) a favor o en contra de los proyectos de un usuario, exagerar o alterar artificialmente los votos \u00abMe gusta\u00bb, los comentarios, etc., dar o recibir dinero u otro tipo de compensaci\u00f3n a cambio de los votos \u00abMe gusta\u00bb o participar en cualquier otra iniciativa organizada que, de cualquier manera, modifique artificialmente los resultados de los Servicios. * Para exhibir cualquier otro comportamiento que restrinja o inhiba a cualquier persona a la hora de utilizar los Servicios, o disfrutar de ellos, o que, como podamos determinar, pueda perjudicar a <strong>MI PLATAFORMA EDUCATIVA<\/strong> o a los usuarios de los Servicios, o exponerlos a responsabilidades. Adem\u00e1s, acepta no: * Saltarse cualquier medida que podamos tomar para evitar o restringir el acceso a los Servicios. * Utilizar los Servicios de cualquier manera que pueda inhabilitar, sobrecargar, da\u00f1ar o menoscabar los Servicios, o interferir en el uso del Sitio de cualquier otra parte, incluida su capacidad para realizar actividades en tiempo real a trav\u00e9s del Sitio. * Usar cualquier robot, ara\u00f1a u otro dispositivo, proceso o medio autom\u00e1tico para acceder a los Servicios con cualquier finalidad, incluidas la supervisi\u00f3n o la copia de cualquier material de los Servicios. * Utilizar cualquier proceso manual para supervisar o copiar cualquier material de los Servicios, o con cualquier otra finalidad no autorizada expresamente en estas Condiciones de uso, sin nuestro previo consentimiento por escrito. * Usar cualquier dispositivo, software o rutina que interfiera en el funcionamiento correcto de los Servicios. * Introducir virus, troyanos, gusanos, bombas l\u00f3gicas u otro material malicioso o tecnol\u00f3gicamente da\u00f1ino. * Obtener o intentar obtener materiales o informaci\u00f3n a trav\u00e9s de cualquier medio que no est\u00e9 intencionalmente disponible o se proporcione a trav\u00e9s del Servicio. * Intentar acceder sin autorizaci\u00f3n, interferir, da\u00f1ar o alterar cualquier parte de los Servicios, el servidor en el que se almacenan los Servicios, o cualquier servicio, ordenador o base de datos conectado a los Servicios o a cuentas privadas de otros usuarios. * Atacar a los Servicios a trav\u00e9s de un ataque de denegaci\u00f3n de servicio o de denegaci\u00f3n de servicio distribuida. * Intentar de cualquier otra manera interferir en el funcionamiento correcto de los Servicios. <strong>MI PLATAFORMA EDUCATIVA<\/strong> tendr\u00e1 el derecho de retirar cualquier contenido que infrinja las Condiciones de uso o sea inaceptable por otros motivos. Si sospecha que se han infringido estas Condiciones de uso (aparte de los avisos de infracci\u00f3n de derechos de autor, tal como se describe a continuaci\u00f3n), contacte con nosotros a trav\u00e9s de nuestro\u00a0email\u00a0<a href=\"mailto:ventas@miplataformaeducativa.com\">ventas@miplataformaeducativa.com<\/a>.\u00a0<strong>4. CONFLICTOS ENTRE USUARIOS.\u00a0<\/strong>Acepta que es exclusivamente responsable de sus interacciones con cualquier otro usuario en relaci\u00f3n con el Servicio y que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no tendr\u00e1 responsabilidad alguna al respecto.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se reserva el derecho, aunque no tiene obligaci\u00f3n alguna, de intervenir de cualquier manera en los conflictos entre usted y cualquier otro usuario del Servicio.\u00a0<strong>5. PROPIEDAD INTELECTUAL. 5.1. DERECHOS DE PROPIEDAD INTELECTUAL DE MI PLATAFORMA EDUCATIVA.\u00a0<\/strong>Los Servicios y las caracter\u00edsticas, las funciones y el contenido relacionados (incluidos, entre otros, la informaci\u00f3n, el software, el texto, las pantallas, las im\u00e1genes, los v\u00eddeos, los audios, el dise\u00f1o, la selecci\u00f3n y la disposici\u00f3n) son propiedad de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, de sus licenciadores o de otros proveedores de este tipo de materiales, y est\u00e1n protegidos en virtud de la legislaci\u00f3n de derechos de autor, marcas comerciales, patentes, secretos comerciales y de otras leyes de propiedad intelectual o de derechos de propiedad, ya sean estadounidenses o internacionales. Estas Condiciones de uso le permiten utilizar el Sitio web \u00fanicamente con car\u00e1cter personal y no comercial. Al acceder a los Servicios o comprar un curso, le concedemos una licencia limitada, no exclusiva y no transferible para acceder al contenido de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0y visualizar los cursos a trav\u00e9s de los Servicios solo en modo de retransmisi\u00f3n en directo con esa finalidad. Salvo la licencia limitada mencionada anteriormente, no se le transfiere ning\u00fan derecho, t\u00edtulo o inter\u00e9s en los Servicios o cualquier contenido de ellos, y\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se reserva todos los derechos no concedidos expresamente.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0puede revocar su licencia en cualquier momento y seg\u00fan su criterio exclusivo.\u00a0<strong>No debe reproducir, distribuir, modificar, crear trabajos derivados, mostrar o reproducir p\u00fablicamente, volver a publicar, descargar, almacenar o transmitir cualquiera de los materiales de nuestros Servicios.\u00a0<\/strong>El nombre y el logotipo de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, as\u00ed como todos los nombres, logotipos, nombres de productos y servicios, dise\u00f1os y esl\u00f3ganes relacionados, son marcas comerciales de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, sus empresas filiales o licenciadores. No debe usar estas marcas sin nuestro previo permiso por escrito. Todos los otros nombres, logotipos, nombres de productos y servicios, dise\u00f1os y esl\u00f3ganes de este Servicio son marcas comerciales de sus respectivos propietarios. No debe eliminar ni alterar ning\u00fan aviso de derechos de autor, de marca comercial o de otro derecho de propiedad de cualquier material del Sitio. Utilizar el Sitio de cualquier manera que estas Condiciones de uso no permitan expresamente constituir\u00e1 una infracci\u00f3n de estas Condiciones de uso y podr\u00eda infringir la legislaci\u00f3n de derechos de autor o de marca comercial, u otras leyes.\u00a0<strong>5.2. CONTRIBUCIONES DEL USUARIO.\u00a0<\/strong>Usted mantendr\u00e1 todos los derechos y la propiedad de sus fotograf\u00edas, im\u00e1genes, v\u00eddeos, sonidos o cualquier otro contenido o material que cargue a trav\u00e9s de los Servicios o comparta con otros usuarios o destinatarios.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no reclama ning\u00fan derecho de propiedad sobre sus Contribuciones del usuario. No obstante, al proporcionar o cargar cualquier Contribuci\u00f3n del usuario concede por el presente documento a\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, a sus empresas filiales y a sus proveedores de servicios (y a cada uno de sus respectivos licenciadores, sucesores y cesionarios) una licencia no exclusiva, internacional, libre de regal\u00edas, completamente pagada, transferible, sublicenciable, perpetua e irrevocable para copiar, reproducir, cargar, almacenar, distribuir (a trav\u00e9s de m\u00faltiples niveles de distribuci\u00f3n y de asociaciones), modificar, adaptar, reproducir y mostrar p\u00fablicamente, publicar, utilizar y explotar completamente dicha Contribuci\u00f3n del usuario en cualquier medio, forma, tecnolog\u00eda o m\u00e9todo de distribuci\u00f3n conocido en la actualidad o desarrollado en el futuro, y con cualquier finalidad (comercial o de otro tipo).\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0siempre le reconocer\u00e1 los cr\u00e9ditos correspondientes al utilizar sus Contribuciones del usuario. Adem\u00e1s, al cargar sus Contribuciones del usuario concede a otros usuarios, visitantes y profesores de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0el derecho de compartir dichas Contribuciones del usuario a trav\u00e9s de las plataformas de redes sociales integradas en\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0(como Instagram, Pinterest, Facebook o Twitter). Para rescindir esta licencia en cualquier momento, retire sus Contribuciones del usuario de los Servicios. En la medida que sea razonable,\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se encargar\u00e1 de retirar este contenido de los Servicios en caso de que usted decida eliminarlo, pero debe saber que el registro en la memoria cach\u00e9 o las referencias a dicho contenido tal vez no dejen de estar disponibles inmediatamente. Debe saber y acepta que cualquier pregunta, comentario, sugerencia, idea, opini\u00f3n u otro tipo de informaci\u00f3n pertinente para el Servicio que proporcione a\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, a sus empresas filiales y a sus proveedores de servicios (y a cada uno de sus respectivos licenciadores, sucesores y cesionarios) y a otros usuarios, visitantes y profesores de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no ser\u00e1 confidencial y que dichas partes estar\u00e1n autorizadas a utilizar y difundir estos Env\u00edos sin restricciones y de manera perpetua con cualquier finalidad, ya sea comercial o de otro tipo, de cualquier manera y en cualquier medio sin ning\u00fan reconocimiento ni compensaci\u00f3n para usted. Declara y garantiza que: (i) Posee o controla todos los derechos, t\u00edtulos e intereses en las Contribuciones del usuario y tiene el derecho de conceder las licencias concedidas anteriormente; y (ii) todas sus Contribuciones del usuario y todos sus Env\u00edos cumplen y cumplir\u00e1n estas Condiciones de uso. Entiende y reconoce que es responsable de todas las Contribuciones del usuario y de todos los Env\u00edos que env\u00ede o aporte como contribuci\u00f3n y usted, no\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, es completamente responsable de estos contenidos, incluidas su legalidad, fiabilidad, exactitud y adecuaci\u00f3n.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no es responsable ante nadie del contenido o de la exactitud de cualquier Contribuci\u00f3n del usuario o Env\u00edo que usted o cualquier otro usuario de los Servicios publiquen (incluido, entre otros casos, de los errores o las omisiones en cualquier contenido o de cualquier p\u00e9rdida o da\u00f1o de cualquier tipo causado por el uso de dicho contenido). Reconoce que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no analiza previamente el contenido y que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0y sus personas designadas tendr\u00e1n el derecho (pero no la obligaci\u00f3n), seg\u00fan su criterio exclusivo, de rechazar o retirar cualquier contenido disponible a trav\u00e9s de los Servicios. Sin limitar lo anterior,\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0y sus personas designadas tendr\u00e1n el derecho de retirar cualquier contenido que infrinja estas Condiciones de uso o que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0considere, seg\u00fan su criterio exclusivo, inaceptable por cualquier otro motivo. No tenemos ninguna obligaci\u00f3n de conservar ninguna Contribuci\u00f3n del usuario que haya publicado durante cualquier per\u00edodo de tiempo m\u00e1s all\u00e1 de lo que la legislaci\u00f3n vigente exija. Tambi\u00e9n entiende y reconoce que terceras partes pueden copiar ilegalmente, sin su o nuestro consentimiento, sus Contribuciones del usuario publicadas en los Servicios a pesar de que procuremos de manera razonable evitar estas actividades ilegales. Acepta y entiende que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no ser\u00e1 responsable ante usted de cualquier copia ilegal de sus Contribuciones del usuario.\u00a0<strong>6. SUPERVISI\u00d3N Y APLICACI\u00d3N; RESCISI\u00d3N.\u00a0MI PLATAFORMA EDUCATIVA<\/strong>\u00a0tiene el derecho de: * Retirar cualquier Contribuci\u00f3n del usuario o Env\u00edo por cualquier o ninguna raz\u00f3n, y seg\u00fan nuestro criterio exclusivo. * Tomar cualquier medida con relaci\u00f3n a cualquier Contribuci\u00f3n del usuario que consideremos necesaria o apropiada, seg\u00fan nuestro criterio exclusivo, incluido el caso de que creamos que dicha Contribuci\u00f3n del usuario infringe las Condiciones de uso, vulnera cualquier derecho de propiedad intelectual u otro derecho de cualquier persona o entidad, amenaza la seguridad personal de los usuarios de los Servicios o del p\u00fablico en general, o puede crear cualquier responsabilidad para\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>. * Revelar su identidad u otra informaci\u00f3n sobre usted a cualquier tercero que reclame que el material que usted ha publicado vulnera sus derechos, incluidos sus derechos de propiedad intelectual o de privacidad. * Tomar medidas legales apropiadas, incluida, entre otras, la derivaci\u00f3n del caso a la polic\u00eda, ante cualquier uso ilegal o no autorizado de los Servicios. * Rescindir o suspender su acceso a los Servicios, en su totalidad o en parte, por cualquier o ninguna raz\u00f3n, incluidas, entre otras, (i) cualquier infracci\u00f3n de estas Condiciones de uso, (ii) el impago de cualquier importe que usted deba, (iii) la presentaci\u00f3n de solicitudes de retroceso de cargos fraudulentas, (iv) si sospechamos que usted est\u00e1 implicado en actividades fraudulentas o ilegales, o (v) por cualquier otra raz\u00f3n, seg\u00fan nuestro criterio razonable exclusivo. Acepta que cualquier rescisi\u00f3n de su acceso al Servicio en virtud de cualquier estipulaci\u00f3n de estas Condiciones de uso puede entrar en vigor sin previo aviso y reconoce y acepta que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0puede desactivar o eliminar inmediatamente su cuenta, as\u00ed como toda la informaci\u00f3n relacionada y los archivos de la cuenta, o prohibir cualquier acceso posterior a dichos archivos o al Servicio. Adem\u00e1s, acepta que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no ser\u00e1 responsable ante usted ni ante ning\u00fan tercero de cualquier rescisi\u00f3n de su acceso al Servicio. Sin limitar lo anterior, tenemos el derecho de cooperar plenamente con cualquier autoridad policial u orden judicial que nos solicite o nos indique que revelemos la identidad o cualquier otra informaci\u00f3n de cualquier persona que publique cualquier material en los Servicios o a trav\u00e9s de ellos. USTED RENUNCIA Y EXONERA A LA EMPRESA Y A SUS FILIALES, LICENCIADORES Y PROVEEDORES DE SERVICIOS DE CUALQUIER RECLAMACI\u00d3N QUE RESULTE DE CUALQUIER MEDIDA QUE TOME CUALQUIERA DE LAS PARTES MENCIONADAS ANTERIORMENTE O COMO RESULTADO DE SUS INVESTIGACIONES, Y DE CUALQUIER MEDIDA TOMADA COMO CONSECUENCIA DE LAS INVESTIGACIONES DE DICHAS PARTES O DE LAS AUTORIDADES POLICIALES. No obstante, no nos comprometemos a revisar el material antes de publicarse en el Servicio ni podemos asegurar la pronta retirada del material inaceptable una vez publicado. En consecuencia, no asumimos ninguna responsabilidad por cualquier acci\u00f3n o inacci\u00f3n relativa a las transmisiones, las comunicaciones o el contenido que cualquier usuario o tercero proporcionen. No tenemos ninguna responsabilidad ante nadie por la realizaci\u00f3n o la no realizaci\u00f3n de las actividades descritas en esta secci\u00f3n.\u00a0<strong>7. CONFIANZA EN LA INFORMACI\u00d3N PUBLICADA.\u00a0<\/strong>La informaci\u00f3n presentada en los Servicios, o a trav\u00e9s de ellos, est\u00e1 disponible \u00fanicamente con finalidades de informaci\u00f3n general. No garantizamos que esta informaci\u00f3n sea exacta, completa o \u00fatil. Usted debe confiar en esta informaci\u00f3n estrictamente bajo su propio riesgo. Recusamos cualquier responsabilidad que surja de la confianza que usted, cualquier otro visitante de los Servicios o cualquier persona que pueda estar informada de cualquiera de sus contenidos depositen en estos materiales. Los Servicios pueden incluir contenido proporcionado por terceros, incluidos los materiales proporcionados por otros usuarios, titulares de blogs, licenciadores, sindicadores, agregadores o servicios de informes.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no ha revisado, y no puede revisar, todos los materiales publicados en los Servicios. Todas las declaraciones u opiniones expresadas en estos materiales, y todos los art\u00edculos, las respuestas a preguntas y otro tipo de contenido, aparte del contenido que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0proporcione, son exclusivamente las opiniones y la responsabilidad de la persona o la entidad que proporcionen estos materiales. Estos materiales no reflejan necesariamente la opini\u00f3n de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>. No somos responsables, ante usted ni ante ning\u00fan tercero, del contenido o de la exactitud de cualquier material que cualquier tercero haya proporcionado.\u00a0<strong>8. ENLACE A LOS SERVICIOS Y A LAS CARACTER\u00cdSTICAS DE REDES SOCIALES.\u00a0<\/strong>Puede enlazar a nuestra p\u00e1gina de inicio, siempre que lo haga de una manera justa y legal y que no da\u00f1e nuestra reputaci\u00f3n ni se aproveche de ella, pero no debe establecer ning\u00fan enlace de una manera que sugiera cualquier forma de asociaci\u00f3n, aprobaci\u00f3n o promoci\u00f3n por parte nuestra sin nuestro consentimiento expreso por escrito. Los Servicios pueden proporcionar ciertas caracter\u00edsticas de redes sociales que le permiten: * Enlazar desde su propio sitio web, o el de determinados terceros, a cierto contenido de este Sitio. * Enviar correos electr\u00f3nicos u otras comunicaciones con cierto contenido, o enlaces a cierto contenido, de este Sitio. * Hacer que partes limitadas de contenido de este Sitio se muestren en su propio sitio web o en el de determinados terceros. * Puede utilizar estas caracter\u00edsticas exclusivamente como las proporcionamos y \u00fanicamente con relaci\u00f3n al contenido con el que se muestran. Teniendo en cuenta lo anterior, no debe: * Establecer ning\u00fan enlace desde cualquier sitio web que no sea de su propiedad. * Hacer que el Sitio, o partes de \u00e9l, se muestren en cualquier otro sitio, a trav\u00e9s, por ejemplo, de la integraci\u00f3n mediante marcos o del establecimiento de enlaces profundos o en l\u00ednea. * Enlazar a cualquier parte del Sitio que no sea la p\u00e1gina de inicio. * Tomar cualquier medida con relaci\u00f3n a los materiales del Sitio que contravenga cualquier otra estipulaci\u00f3n de estas Condiciones de uso. Recuerde que la manera en la que los servicios de redes sociales utilizan, almacenan y divulgan su informaci\u00f3n se rige \u00fanicamente por las pol\u00edticas de dichos terceros y que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no tendr\u00e1 ninguna responsabilidad por las pr\u00e1cticas de privacidad u otras acciones de cualquier sitio o servicio de terceros que pueda estar habilitado en el Servicio. Adem\u00e1s,\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no es responsable de la exactitud, la disponibilidad o la fiabilidad de cualquier informaci\u00f3n, contenido, bien, dato, opini\u00f3n, consejo o declaraci\u00f3n disponible con relaci\u00f3n a los servicios de redes sociales. En consecuencia,\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no es responsable de cualquier da\u00f1o o p\u00e9rdida causado o presuntamente causado por o en relaci\u00f3n con el uso de dichos servicios de redes sociales, o la confianza depositada en ellos.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0habilita estas caracter\u00edsticas meramente como una comodidad, y la integraci\u00f3n o la inclusi\u00f3n de dichas caracter\u00edsticas no implica ninguna promoci\u00f3n ni recomendaci\u00f3n. Acepta cooperar inmediatamente con nosotros para dejar de realizar acciones no autorizadas de integraci\u00f3n mediante marcos o establecimiento de enlaces. Nos reservamos el derecho de retirar el permiso para enlazar sin previo aviso. Podemos inhabilitar todas o cualquiera de las caracter\u00edsticas de redes sociales y cualquier enlace en cualquier momento sin previo aviso, seg\u00fan nuestro criterio exclusivo.\u00a0<strong>9. ENLACES DESDE LOS SERVICIOS.\u00a0<\/strong>Si nosotros, o terceros, proporcionamos enlaces a otros sitios y recursos de terceros, estos enlaces se proporcionan \u00fanicamente para su comodidad. Algunos ejemplos pueden ser los enlaces contenidos en anuncios, incluidos los anuncios de\u00a0<em>banner<\/em>\u00a0y los enlaces patrocinados. No tenemos control sobre los contenidos de estos sitios o recursos ni aceptamos ninguna responsabilidad por ellos ni por cualquier p\u00e9rdida o da\u00f1o que pueda surgir al utilizarlos. Si decide acceder a cualquiera de los sitios web de terceros enlazados desde los Servicios, lo har\u00e1 completamente bajo su propio riesgo y de acuerdo con las condiciones de uso de dichos sitios web.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se reserva el derecho de retirar cualquier enlace proporcionado por terceros en los Servicios.\u00a0<strong>10. TARIFAS.\u00a0<\/strong>Para utilizar los cursos en l\u00ednea y otros Servicios que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0ofrece es necesario pagar una tarifa. Acepta pagar las tarifas del contenido que compre y autoriza a\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0a cobrarle los Servicios con el m\u00e9todo de pago que seleccione. Las tarifas se cobrar\u00e1n tanto si utiliza los Servicios comprados como si no. Es responsable de pagar puntualmente todas las tarifas que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0cobre, as\u00ed como los impuestos aplicables. Nos reservamos el derecho de inhabilitar o retirar el acceso a cualquier contenido por el que no hayamos recibido un pago adecuado. Las tarifas pueden variar seg\u00fan su ubicaci\u00f3n y otros factores. Si tiene la sesi\u00f3n iniciada en su cuenta, la moneda que ver\u00e1 seleccionada se basar\u00e1 en su ubicaci\u00f3n en el momento de crear la cuenta. No obstante, las tarifas finales que le cobremos se calcular\u00e1n siempre en pesos mexicanos; por tanto, dichas tarifas finales pueden variar en funci\u00f3n de las tasas de cambio de divisas prevalentes que nuestros proveedores de pago ofrezcan. Ocasionalmente, realizamos promociones y rebajas para nuestro contenido, en las que determinado contenido est\u00e1 disponible a precios con descuento durante cierto per\u00edodo de tiempo. El precio aplicable al contenido ser\u00e1 el precio en el momento en el que compr\u00f3 el contenido. Proporcionar\u00e1 a\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0informaci\u00f3n sobre su tarjeta de cr\u00e9dito u otro instrumento de pago. Declara y garantiza que (a) esta informaci\u00f3n es veraz, exacta, actual y completa, y que est\u00e1 autorizado a utilizar este instrumento de pago, y (b) mantendr\u00e1 y actualizar\u00e1 puntualmente esta informaci\u00f3n para que siga siendo veraz, exacta, actual y completa. Acepta que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0puede actualizar sus m\u00e9todos de pago con la informaci\u00f3n que nuestros proveedores de servicios de pago nos proporcionen y nos autoriza a seguir cobrando las tarifas vigentes en su m\u00e9todo de pago actualizado.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se reserva el derecho, en cualquier momento, de cambiar cualquier tarifa o de comenzar a cobrar cualquier Servicio hasta entonces gratuito, seg\u00fan su propio criterio exclusivo. Cualquier cambio, actualizaci\u00f3n o modificaci\u00f3n ser\u00e1 efectivo inmediatamente al publicarlo a trav\u00e9s de los Servicios pertinentes (estos cambios no se aplicar\u00e1n a las tarifas pagadas antes de realizarlos). Tenga en cuenta que debido a los sistemas de precios de los proveedores de plataformas m\u00f3viles y de sus pol\u00edticas, es posible que, en ocasiones, el precio del contenido ofrecido en el sitio web de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no sea el mismo que el precio ofrecido en nuestras aplicaciones m\u00f3viles.\u00a0<strong>12. REEMBOLSOS.\u00a0<\/strong>Tenga en cuenta que nuestra pol\u00edtica de reembolsos distingue entre los pagos \u00fanicos para los cursos: (i) Los reembolsos no est\u00e1n disponibles para las cuentas que infrinjan estas Condiciones de uso o que, seg\u00fan el criterio exclusivo y absoluto de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, sean inaceptables por cualquier otro motivo; (ii) si\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0determina que usted hace un uso inadecuado de nuestra pol\u00edtica de reembolsos, nos reservamos el derecho de suspender o rescindir su cuenta y de denegar o restringir cualquier uso actual o futuro del Servicio sin realizar ning\u00fan reembolso; (iii) para solicitar un reembolso, contacte con nosotros a trav\u00e9s de nuestro\u00a0correo electr\u00f3nico soporte@miPLATAFORMAeducativa.com; (iv)\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0aplicar\u00e1 su reembolso a su m\u00e9todo de pago original; (v) lamentablemente, en este momento, no podemos ofrecer reembolsos parciales para sus compras. Si dentro de los primeros 14 d\u00edas despu\u00e9s de comprar un curso no est\u00e1 conforme con dicho curso,\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0le reembolsar\u00e1 el importe completo de su compra y rescindir\u00e1 posteriormente su acceso al curso. No podremos realizar ning\u00fan reembolso solicitado despu\u00e9s de este per\u00edodo de 14 d\u00edas. Adem\u00e1s de lo anterior, si compra un curso, o cualquier otro servicio de pago, a trav\u00e9s de un dispositivo m\u00f3vil o de una tienda digital de terceros (por ejemplo, las compras realizadas a trav\u00e9s de Apple App Store o Google Play App Store), se aplicar\u00e1 la pol\u00edtica de reembolsos vigente en esa tienda digital de terceros, salvo que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0establezca expl\u00edcitamente lo contrario. Excepto si\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0lo establece expl\u00edcitamente de alguna otra manera, la tienda digital de terceros ser\u00e1 exclusivamente responsable de realizar los reembolsos de acuerdo con su pol\u00edtica de reembolsos y\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no tendr\u00e1 ninguna obligaci\u00f3n de efectuar ning\u00fan reembolso.\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0recusa cualquier responsabilidad relacionada con la pol\u00edtica de reembolsos de cualquier tienda digital de terceros o con el cumplimiento o el incumplimiento de esa pol\u00edtica por parte de dichos terceros.\u00a0<strong>15. RENUNCIA DE GARANT\u00cdAS.\u00a0<\/strong>Usted debe entender que no podemos garantizar, y no garantizamos, que los archivos disponibles para descargar desde Internet o los Servicios no tengan virus u otro c\u00f3digo destructivo. Debe implementar suficientes procedimientos y puntos de control para satisfacer sus requisitos particulares de protecci\u00f3n antivirus y de exactitud en la entrada y la salida de datos; tambi\u00e9n debe tener instalado un medio externo a nuestro sitio para restaurar cualquier dato perdido. No seremos responsables de cualquier p\u00e9rdida o da\u00f1o causado por un ataque de denegaci\u00f3n de servicio distribuida, por virus o por otro material tecnol\u00f3gicamente da\u00f1ino que pueda infectar su ordenador, sus programas inform\u00e1ticos, sus datos u otro material de su propiedad debido a que usted haya utilizado el sitio o cualquiera de los servicios, obtenido elementos a trav\u00e9s de los servicios o descargado cualquier material publicado en el sitio o en cualquier sitio web enlazado en \u00e9l. Usted utiliza el sitio, su contenido y cualquier servicio o elemento obtenido a trav\u00e9s del sitio bajo su propio riesgo. El sitio, su contenido y cualquier servicio o elemento obtenido a trav\u00e9s del sitio se proporcionan \u00abtal cual\u00bb y \u00abseg\u00fan disponibilidad\u00bb, sin ninguna garant\u00eda de ning\u00fan tipo, ya sea expresa o impl\u00edcita. Ni la empresa ni ninguna persona asociada a la empresa garantizan ni declaran la integridad, seguridad, fiabilidad, calidad, exactitud o disponibilidad del sitio. Sin limitar lo anterior, ni la empresa ni ninguna persona asociada a la empresa garantizan ni declaran que el sitio, su contenido o cualquier servicio o elemento obtenido a trav\u00e9s del sitio sean exactos y fiables, que no tengan virus ni interrupciones, que se corregir\u00e1n los defectos relacionados, que nuestro sitio o el servidor desde el que est\u00e1 disponible no tengan virus u otros componentes da\u00f1inos o que el sitio o cualquier servicio o elemento obtenido a trav\u00e9s del sitio cumplan sus necesidades o expectativas. Por el presente documento, la empresa recusa todas las garant\u00edas de cualquier tipo, ya sean expresas o impl\u00edcitas, estatutarias o de otro tipo, incluidas, entre otras, las garant\u00edas de comercializaci\u00f3n, no infracci\u00f3n e idoneidad para una finalidad concreta. Lo anterior no afecta a cualquier garant\u00eda que no se pueda excluir o limitar en virtud de la legislaci\u00f3n vigente.\u00a0<strong>16. LIMITACI\u00d3N DE RESPONSABILIDAD.\u00a0<\/strong>En la medida m\u00e1xima que la legislaci\u00f3n contemple,\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, sus empresas filiales o sus licenciadores, proveedores de servicios, empleados, agentes, directivos o directores no ser\u00e1n responsables en ning\u00fan caso de los da\u00f1os de cualquier tipo, en virtud de cualquier teor\u00eda legal, producidos por o en relaci\u00f3n con el hecho de que utilice, o no pueda utilizar, el sitio, cualquier sitio web enlazado en \u00e9l, cualquier contenido del sitio o de otros sitios web o cualquier servicio o elemento obtenido a trav\u00e9s del sitio o de esos otros sitios web, incluidos los da\u00f1os directos, indirectos, especiales, incidentales, emergentes o punitivos, como por ejemplo, entre otros, lesi\u00f3n personal dolor y sufrimiento, fatiga emocional, p\u00e9rdida de ingresos, de beneficios, de oportunidades comerciales, de ahorros previstos, de uso, de fondos de comercio o de datos, y tanto si la causa es un agravio (incluida la negligencia), un incumplimiento de contrato o cualquier otro motivo, aun en el caso de que fuera previsible. La responsabilidad total de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0con usted por todos los da\u00f1os, las p\u00e9rdidas o las causas de acci\u00f3n no superar\u00e1 en ning\u00fan caso el importe que haya pagado a\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0en los \u00faltimos seis (6) meses o $2,000.00 MX, en caso de que dicho importe sea superior. En algunas jurisdicciones, no se permite la exclusi\u00f3n de ciertas garant\u00edas o la limitaci\u00f3n o la exclusi\u00f3n de responsabilidad por da\u00f1os incidentales o emergentes. En consecuencia, es posible que algunas de las limitaciones indicadas anteriormente no se apliquen en su caso. Si no est\u00e1 satisfecho con cualquier parte del servicio o con estas condiciones del servicio, solo tiene la opci\u00f3n de dejar de utilizarlo.\u00a0<strong>17. INDEMNIZACI\u00d3N.\u00a0<\/strong>Acepta defender, indemnizar y exonerar a\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, a sus empresas filiales, licenciadores y proveedores de servicio, as\u00ed como a sus respectivos directivos, directores, empleados, contratistas, agentes, licenciadores, proveedores, sucesores y cesionarios de cualquier reclamaci\u00f3n, responsabilidad, da\u00f1o, proceso y fallo judicial, p\u00e9rdida, coste, gasto o tarifa (incluidos los honorarios razonables de abogados) que se haya producido a causa de o en relaci\u00f3n con el hecho de que usted haya infringido estas condiciones de uso o la manera establecida de utilizar el servicio, incluidos, entre otros, sus contribuciones del usuario, cualquier uso del contenido, de los servicios y de los productos del servicio que no sea el que se autoriza expresamente en estas condiciones de uso, o su uso de cualquier informaci\u00f3n obtenida a trav\u00e9s del servicio.\u00a0<strong>18. LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N.\u00a0\u00a0<\/strong>Todos los asuntos relacionados con los servicios y estas condiciones de uso, as\u00ed como cualquier conflicto o reclamaci\u00f3n que surja de dichos servicios y condiciones o est\u00e9 relacionado con ellos (en cada caso, incluidos los conflictos o las reclamaciones no contractuales) se regir\u00e1n por la legislaci\u00f3n interna de M\u00e9xico, y se interpretar\u00e1n de acuerdo con dicha legislaci\u00f3n, sin dar efecto a ninguna estipulaci\u00f3n o regla de conflicto de leyes.\u00a0<strong>19. RESOLUCI\u00d3N DE CONFLICTOS.\u00a0<\/strong><em>Con car\u00e1cter general.<\/em>\u00a0En inter\u00e9s de resolver los conflictos entre usted y\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0de la manera m\u00e1s conveniente y rentable, usted y\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0aceptan que cualquier conflicto que surja de, o est\u00e9 relacionado de cualquier manera con, estas condiciones de uso, su uso del sitio o de los servicios, o de la compra, el recibo, el pedido de compra o el uso de cualquier curso se resolver\u00e1 mediante arbitraje vinculante. El arbitraje es menos formal que un proceso judicial en un tribunal. En el arbitraje interviene un \u00e1rbitro neutral en lugar de un juez o un jurado; los \u00e1rbitros pueden fallar sobre los mismos perjuicios y compensaciones que un tribunal.\u00a0<strong>Entiende y acepta que, al asumir estas condiciones, renuncia al derecho de celebrar un juicio por jurado o de participar en una demanda colectiva.\u00a0<\/strong><em>Excepciones.<\/em>\u00a0A pesar de las estipulaciones de la secci\u00f3n anterior titulada \u00abcon car\u00e1cter general\u00bb, ninguna parte de estas condiciones de uso se considerar\u00e1 una renuncia, impedir\u00e1 o limitar\u00e1 de cualquier otra manera el derecho de cualquiera de las partes a: (a) reclamar una acci\u00f3n ejecutiva a trav\u00e9s de la agencia federal, estatal o local aplicable si dicha acci\u00f3n est\u00e1 disponible; (b) solicitar una orden judicial en un juzgado; o (c) presentar una demanda en un juzgado para realizar una reclamaci\u00f3n de vulneraci\u00f3n de la propiedad intelectual.\u00a0<em>\u00c1rbitro.<\/em>\u00a0Cualquier arbitraje entre usted y\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se regir\u00e1 por la ley de arbitraje de los estados unidos mexicanos.\u00a0<strong>20. LIMITACI\u00d3N TEMPORAL PARA PRESENTAR RECLAMACIONES.\u00a0<\/strong>Cualquier causa de acci\u00f3n o reclamaci\u00f3n que usted pueda tener que surja de, o est\u00e9 en relaci\u00f3n con, estas condiciones de uso o el servicio se debe iniciar dentro de un (1) a\u00f1o despu\u00e9s de hacer valer el derecho de causa de acci\u00f3n; de lo contrario, dicha causa de acci\u00f3n o reclamaci\u00f3n se bloquear\u00e1 permanentemente.<strong>21. RENUNCIA Y DIVISIBILIDAD.\u00a0<\/strong>Ninguna renuncia por parte de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0a cualquier condici\u00f3n establecida en estas condiciones de uso se considerar\u00e1 una renuncia adicional o continuada a dicha condici\u00f3n ni una renuncia a cualquier otra condici\u00f3n, y el hecho de que\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0no reafirme un derecho o una estipulaci\u00f3n en virtud de estas condiciones de uso no constituir\u00e1 una renuncia a dicho derecho o a dicha estipulaci\u00f3n. Si un tribunal u otro juzgado con jurisdicci\u00f3n competente declaran cualquier estipulaci\u00f3n de estas condiciones de uso como no v\u00e1lida, ilegal o no ejecutable por cualquier raz\u00f3n, dicha estipulaci\u00f3n se eliminar\u00e1 o se limitar\u00e1 al m\u00ednimo de manera que las otras estipulaciones de las condiciones de uso continuar\u00e1n siendo efectivas y vigentes.\u00a0<strong>22. SIN TERCEROS BENEFICIARIOS Y ASIGNACI\u00d3N.\u00a0<\/strong>Acepta que, salvo si se indica expresamente lo contrario en estas condiciones de uso, en este acuerdo no habr\u00e1 terceros beneficiarios. No puede asignar estas condiciones de uso sin el previo consentimiento por escrito de\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>, pero\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0puede asignar o transferir estas condiciones de uso, en parte o en su totalidad, sin restricci\u00f3n alguna.\u00a0<strong>23. ACUERDO COMPLETO.\u00a0<\/strong>Las condiciones de uso constituyen el \u00fanico acuerdo completo entre usted y\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0con relaci\u00f3n a los servicios y sustituyen a todos los pactos, las declaraciones, las garant\u00edas y los acuerdos, tanto escritos como orales, relacionados con los servicios.\u00a0<strong>24. USO HORARIO.\u00a0<\/strong>Salvo que se indique expresamente lo contrario, con el objetivo de mantener un est\u00e1ndar global y garantizar la coherencia en nuestros servicios, todos los plazos y horarios informados por\u00a0<strong>MI PLATAFORMA EDUCATIVA<\/strong>\u00a0se basan en el horario UTC.\u00a0<strong>25. IDIOMA.\u00a0<\/strong>Cualquier versi\u00f3n de estas condiciones de uso en otro idioma que no sea el espa\u00f1ol se proporciona para la comodidad del usuario, y usted entiende y acepta que la versi\u00f3n en espa\u00f1ol prevalecer\u00e1 en caso de cualquier conflicto.\u00a0<strong>26. SUS COMENTARIOS Y DUDAS.\u00a0<\/strong>Puede enviarnos cualquier opini\u00f3n, comentario, solicitud de asistencia t\u00e9cnica o cualquier otra comunicaci\u00f3n relacionada con los servicios a trav\u00e9s de nuestro\u00a0email\u00a0<a href=\"mailto:ventas@miplataformaeducativa.com\">ventas@miplataformaeducativa.com<\/a>. Este sitio web es administrado por HEVER RAUL GARCIA RODRIGUEZ, persona f\u00edsica registrada conforme a la legislaci\u00f3n aplicable. La informaci\u00f3n de identificaci\u00f3n proporcionada en este documento corresponde a los datos registrados ante nuestros proveedores de servicios de pago y autoridades fiscales competentes.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<p>    <!-- version:1784861011 --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes Capacitadores Externos Secretar\u00eda de Trabajo y Previsi\u00f3n social Registro: FTS171122-K12-0013 Ingresa a tu curso Selecci\u00f3n de Cursos Excel B\u00e1sico $199 D\u00f3lares Americanos Excel Avanzado $399 D\u00f3lares Americanos VBA Excel $499 D\u00f3lares Americanos Beneficiados con nuestra capacitaci\u00f3n innovadora + 0 Personas en proceso de formaci\u00f3n + 0 Empresas capacitadas + 0 Trabajadores beneficiados 0 % [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"brizy-blank-template.php","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":31,"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":947,"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/pages\/2\/revisions\/947"}],"wp:attachment":[{"href":"https:\/\/miplataformaeducativa.com\/es\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}